{"id":10346,"date":"2024-06-22T12:05:31","date_gmt":"2024-06-22T12:05:31","guid":{"rendered":"https:\/\/aperahealth.com\/hair-loss\/fue-hair-transplant\/"},"modified":"2024-07-16T14:53:15","modified_gmt":"2024-07-16T14:53:15","slug":"transplante-de-cabello-fue","status":"publish","type":"page","link":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/","title":{"rendered":"Trasplante capilar FUE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10346\" class=\"elementor elementor-10346 elementor-5404\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9aaf5de e-flex e-con-boxed e-con e-parent\" data-id=\"9aaf5de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n    <path class=\"elementor-shape-fill\" d=\"M1000,4.3V0H0v4.3C0.9,23.1,126.7,99.2,500,100S1000,22.7,1000,4.3z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09d414f e-flex e-con-boxed e-con e-child\" data-id=\"09d414f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-543aef8 e-con-full e-flex e-con e-child\" data-id=\"543aef8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5c6ff7 elementor-widget elementor-widget-image\" data-id=\"f5c6ff7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"788\" height=\"525\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg\" class=\"attachment-large size-large wp-image-10347\" alt=\"\" srcset=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg 788w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512-600x400.jpg 600w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512-300x200.jpg 300w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512-768x512.jpg 768w\" sizes=\"(max-width: 788px) 100vw, 788px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddfb103 e-flex e-con-boxed e-con e-child\" data-id=\"ddfb103\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-921befb e-flex e-con-boxed e-con e-child\" data-id=\"921befb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ee70b74 e-con-full e-flex e-con e-child\" data-id=\"ee70b74\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb80196 elementor-widget elementor-widget-heading\" data-id=\"cb80196\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Trasplante capilar FUE<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-482856d e-con-full e-flex e-con e-child\" data-id=\"482856d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48554d9 elementor-widget elementor-widget-image\" data-id=\"48554d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"151\" height=\"177\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/LOGO-YOLIN-ODULU.png\" class=\"attachment-large size-large wp-image-465\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f29c33 elementor-widget elementor-widget-text-editor\" data-id=\"9f29c33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La FUE, o extracci\u00f3n de unidades foliculares, es una t\u00e9cnica quir\u00fargica moderna de trasplante capilar que se utiliza para tratar la ca\u00edda del cabello o la calvicie. Es uno de los m\u00e9todos m\u00e1s avanzados de restauraci\u00f3n capilar y consiste en extraer fol\u00edculos pilosos individuales de una zona donante y trasplantarlos a zonas con poco pelo o sin pelo. La FUE es conocida por su naturaleza m\u00ednimamente invasiva y su capacidad para crear resultados de aspecto natural.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a070318 elementor-mobile-align-center button-primary elementor-widget elementor-widget-button\" data-id=\"a070318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ct-popup-10085\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"30\" height=\"30\" viewBox=\"0 0 30 30\" fill=\"none\"><circle cx=\"15\" cy=\"15\" r=\"13.5\" fill=\"#35B9D9\" stroke=\"#F7FBFD\" stroke-width=\"3\"><\/circle><path d=\"M18.6551 11.3448L11.3447 18.6552M18.6551 11.3448H12.5631M18.6551 11.3448V17.4368\" stroke=\"#F6FBFC\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulta gratuita<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1991ebd e-flex e-con-boxed e-con e-parent\" data-id=\"1991ebd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-340e78d e-grid e-con-full e-con e-child\" data-id=\"340e78d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c54d714 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c54d714\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"74\" height=\"58\" viewBox=\"0 0 74 58\" fill=\"none\"><g opacity=\"0.5\"><path d=\"M10.9214 50.9471C10.9214 52.6306 10.8875 54.2833 10.9343 55.9336C10.9616 56.8934 10.2852 57.6376 9.23879 57.6263C6.72781 57.5991 4.21637 57.6182 1.70507 57.617C0.619303 57.6164 0.0407715 57.0423 0.0408496 55.9571C0.0418647 43.5559 0.0438949 31.1547 0.0470964 18.7535C0.0475649 16.9059 0.00852242 15.0568 0.0720055 13.2112C0.153917 10.8303 2.14329 8.66068 4.49622 8.27931C7.45689 7.7994 10.1116 9.57005 10.7921 12.4952C10.8795 12.8709 10.9156 13.2667 10.9161 13.6532C10.9238 19.3789 10.9214 25.1045 10.9214 30.8302V31.3185H15.444C15.3685 30.6469 15.2285 29.9723 15.2285 29.2976C15.2286 27.045 17.2761 24.8768 19.5266 24.8375C22.8176 24.7801 26.1108 24.7873 29.4022 24.8315C31.4871 24.8596 33.3852 26.6166 33.726 28.6724C33.8744 29.5678 33.7921 30.4298 33.4602 31.3134H63.0822C63.0822 30.5802 63.0821 29.855 63.0822 29.1297C63.0825 27.3993 63.7465 25.9716 65.0638 24.8571C68.1883 22.2136 73.1264 23.9862 73.8593 28.0151C73.931 28.4088 73.9589 28.8155 73.9591 29.2162C73.9648 38.1039 73.9642 46.9916 73.9636 55.8793C73.9634 57.0761 73.4182 57.6171 72.2206 57.6172C69.7351 57.6176 67.2495 57.599 64.7644 57.626C63.7083 57.6374 63.0425 56.8893 63.0694 55.9337C63.1158 54.2835 63.0823 52.6309 63.0823 50.9471H10.9214ZM71.0472 54.6472V54.157C71.048 49.6807 71.0496 45.2046 71.0496 40.7284C71.0497 36.8507 71.0518 32.9731 71.0453 29.0954C71.0425 27.3726 69.4383 26.1575 67.8157 26.6344C66.6929 26.9645 66.0079 27.9464 66.007 29.2511C66.0042 33.6102 65.9877 37.9695 66.0193 42.3284C66.0268 43.3587 65.411 44.0679 64.2664 44.0667C46.1403 44.0471 28.014 44.0529 9.88783 44.0526C9.70566 44.0526 9.51092 44.0889 9.34421 44.0371C9.04272 43.9436 8.72257 43.844 8.47418 43.6605C8.05096 43.3478 7.99466 42.8615 7.9949 42.3609C7.99873 32.9659 7.99787 23.571 7.99685 14.1761C7.99677 13.9161 7.99576 13.6551 7.97475 13.3962C7.9265 12.8038 7.68568 12.2936 7.26762 11.8733C6.54392 11.1459 5.46947 10.929 4.52972 11.311C3.58638 11.6947 2.95795 12.6248 2.95787 13.6643C2.95623 27.2231 2.95654 40.782 2.95756 54.3409C2.95756 54.4408 2.97333 54.5407 2.9827 54.6521H7.99771V54.217C7.99771 52.7206 8.03121 51.2232 7.98678 49.7281C7.95297 48.588 8.71804 47.9972 9.70878 47.9982C27.913 48.0165 46.1173 48.0114 64.3217 48.0119C65.4557 48.0119 65.998 48.543 66.0037 49.6771C66.0113 51.1865 66.0061 52.6959 66.0064 54.2054C66.0065 54.3458 66.0064 54.4863 66.0064 54.6472H71.0472ZM10.9337 41.1096H63.0564V34.3044H10.9337V41.1096ZM24.4971 31.3417V31.3304C26.0571 31.3304 27.6177 31.3565 29.1769 31.3208C30.1457 31.2986 30.8811 30.4777 30.8764 29.5333C30.8716 28.5738 30.1059 27.7345 29.1368 27.7279C26.0556 27.7071 22.9743 27.7054 19.8932 27.7272C18.7904 27.735 17.9985 28.7436 18.1712 29.8239C18.3177 30.7401 19.0305 31.3295 20.0508 31.3384C21.5328 31.3512 23.015 31.3417 24.4971 31.3417Z\" fill=\"#27464E\"><\/path><path d=\"M35.5271 6.63387V5.66663C35.5274 4.41813 35.5231 3.16955 35.5291 1.92105C35.5335 0.995818 36.144 0.3303 36.9847 0.316791C37.8317 0.303126 38.4711 0.985277 38.4749 1.9255C38.481 3.35609 38.4767 4.78677 38.4767 6.21736V6.63394H38.9339C40.3905 6.63402 41.8473 6.62824 43.3039 6.63676C43.9698 6.64066 44.5374 7.06849 44.7169 7.6674C44.9038 8.2913 44.691 8.98102 44.1274 9.3018C43.8382 9.46632 43.4686 9.5551 43.1331 9.5619C41.7421 9.58993 40.3501 9.57361 38.9585 9.57361H38.4765V10.0107C38.4765 11.4284 38.4785 12.846 38.4759 14.2635C38.4741 15.221 37.8729 15.8728 37.0003 15.8718C36.1276 15.8708 35.5294 15.2184 35.528 14.2597C35.5261 12.8551 35.5276 11.4505 35.5277 10.0459V9.57377H35.0808C33.65 9.57369 32.2194 9.5829 30.7888 9.57041C29.7336 9.56112 29.0642 8.7584 29.2672 7.77773C29.4063 7.10573 29.9982 6.63894 30.7437 6.63574C32.1873 6.62957 33.631 6.63387 35.0747 6.63387H35.5271Z\" fill=\"#27464E\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t3 D\u00cdAS\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAlojamiento\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8571635 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8571635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"54\" height=\"59\" viewBox=\"0 0 54 59\" fill=\"none\"><g opacity=\"0.5\"><path d=\"M49.1551 9.32661C49.1706 9.0217 49.1804 8.78634 49.1948 8.5514C49.2742 7.27373 50.3096 6.31412 51.5628 6.35589C52.8294 6.39745 53.8191 7.4007 53.8032 8.68067C53.7721 11.1619 53.7264 13.6433 53.6637 16.1245C53.6284 17.5197 52.4007 18.5545 51.019 18.321C49.0171 17.9834 47.025 17.5872 45.0287 17.2155C44.5246 17.1215 44.0204 17.0279 43.5163 16.9325C42.2048 16.685 41.3782 15.4905 41.624 14.199C41.8606 12.9556 43.0694 12.1518 44.3581 12.3838C44.8395 12.4702 45.3194 12.5634 45.838 12.5928C45.4013 12.1783 44.9813 11.7443 44.5252 11.3527C42.9616 10.0101 41.2659 8.86069 39.4137 7.95183C37.5256 7.02563 35.5523 6.34837 33.4862 5.93821C30.536 5.3518 27.5828 5.31629 24.6223 5.8434C21.0401 6.48098 17.7701 7.85743 14.8163 9.98549C11.7195 12.2169 9.29906 15.0264 7.53313 18.4115C6.33022 20.7168 5.53184 23.1552 5.12941 25.7149C4.70693 28.4037 4.75037 31.0933 5.24594 33.7782C5.83382 36.9634 7.01646 39.9101 8.79263 42.6041C10.6233 45.3812 12.9412 47.6878 15.7407 49.5058C18.7492 51.459 22.0296 52.6788 25.5759 53.1663C29.4427 53.6973 33.2258 53.2882 36.8974 51.9744C39.5714 51.0175 42.0004 49.6148 44.1825 47.786C46.0274 46.2395 47.5759 44.4383 48.9229 42.4502C49.5649 41.5029 50.6732 41.1581 51.6829 41.5365C53.1293 42.0784 53.6201 43.7848 52.7357 45.1034C50.6711 48.1811 48.1517 50.811 45.1016 52.924C42.5949 54.6601 39.8813 55.9672 36.9565 56.8343C34.7487 57.4888 32.4968 57.8659 30.1954 57.9867C27.5722 58.1243 24.9819 57.8929 22.4293 57.3119C19.6789 56.6858 17.0722 55.6692 14.6196 54.2618C11.9542 52.7323 9.60021 50.8271 7.53877 48.547C5.94178 46.7804 4.59374 44.8424 3.48523 42.7432C2.35165 40.5967 1.50732 38.3338 0.958288 35.9653C0.598252 34.4128 0.371663 32.8415 0.262232 31.25C0.054438 28.2237 0.348691 25.2423 1.09362 22.313C1.66249 20.0759 2.50264 17.9347 3.60552 15.8969C5.28875 12.7866 7.45983 10.0799 10.134 7.76429C13.1559 5.14713 16.5877 3.27198 20.3894 2.08432C22.7048 1.3607 25.088 0.95743 27.5187 0.858232C31.8548 0.680511 36.0203 1.42272 40.0158 3.12663C42.4097 4.14701 44.633 5.44995 46.6457 7.09914C47.3978 7.71563 48.1053 8.38621 48.8329 9.03214C48.9237 9.11276 49.0123 9.19587 49.1551 9.32661Z\" fill=\"#27464E\"><\/path><path d=\"M25.9512 20.4675C25.9514 18.3204 25.945 16.1734 25.9546 14.0263C25.9587 13.1116 26.3733 12.4072 27.1798 11.9782C27.9726 11.5564 28.7814 11.5915 29.537 12.0831C30.26 12.5536 30.5912 13.2494 30.591 14.108C30.5906 18.2764 30.5943 22.4448 30.5837 26.6132C30.5828 26.9298 30.6839 27.1041 30.9414 27.2936C32.4323 28.3891 33.0189 29.8685 32.6973 31.6919C32.6558 31.9279 32.6965 32.0739 32.865 32.2409C34.6188 33.9824 36.3668 35.73 38.1108 37.4813C38.9673 38.3417 39.0957 39.5885 38.4397 40.5191C37.5981 41.7128 35.945 41.8558 34.8747 40.811C33.9455 39.9038 33.0352 38.9774 32.1167 38.0592C31.1908 37.1338 30.2696 36.2034 29.3327 35.2889C29.2243 35.183 29.0257 35.1051 28.876 35.1156C26.9526 35.2494 25.2264 34.2117 24.5054 32.4684C23.7854 30.7271 24.2695 28.7538 25.7344 27.5139C25.8965 27.3767 25.979 27.2399 25.951 27.0342C25.9496 27.0239 25.9508 27.0133 25.9508 27.0029C25.9508 24.8245 25.9508 22.6459 25.9512 20.4675ZM28.5005 29.313C27.6654 29.3082 26.9714 29.9945 26.9739 30.8231C26.9762 31.6378 27.6579 32.3238 28.4734 32.3324C29.3052 32.3412 29.9914 31.6576 29.9933 30.8187C29.995 29.9976 29.321 29.3178 28.5005 29.313Z\" fill=\"#27464E\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t10 HORAS\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDuraci\u00f3n del procedimiento\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82391ee elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"82391ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"59\" viewBox=\"0 0 80 59\" fill=\"none\"><g opacity=\"0.5\"><path d=\"M43.9469 12.2763C45.0217 10.6714 45.9208 8.9597 47.1592 7.54484C52.0398 1.96827 58.2446 -0.184417 65.4128 1.61067C72.5445 3.39656 76.8872 8.28606 78.3978 15.4387C79.4772 20.5491 78.9037 25.5761 76.3141 30.2261C74.983 32.6164 73.0518 34.5342 71.1287 36.4476C67.3312 40.2258 63.1932 43.6094 59.0035 46.9338C54.3907 50.5938 49.7816 54.2585 45.1692 57.9186C44.2478 58.6498 43.852 58.6522 42.9274 57.9138C36.4306 52.7255 29.8966 47.5828 23.462 42.3186C20.9334 40.25 18.6221 37.9148 16.2275 35.6843C15.5585 35.0612 15.5258 34.2983 16.0693 33.7521C16.6473 33.1709 17.4243 33.1766 18.0712 33.8362C23.9483 39.8274 30.711 44.7695 37.2153 50.0172C39.3054 51.7034 41.4281 53.3491 43.5116 55.0431C43.9268 55.3808 44.1907 55.3594 44.5914 55.0387C50.3843 50.4023 56.2488 45.8529 61.9666 41.126C65.0288 38.5945 67.881 35.8031 70.7593 33.0571C74.0627 29.9056 75.8848 26.0531 76.167 21.4423C76.4441 16.9182 75.5708 12.7723 72.6721 9.1858C67.0698 2.25475 56.5597 1.78516 50.1237 8.15583C47.0414 11.2068 45.4917 14.9059 45.3549 19.2199C45.3241 20.1899 44.8684 20.7299 44.0648 20.7397C43.2464 20.7496 42.7437 20.1704 42.7154 19.1848C42.4859 11.1774 36.8389 4.88792 28.8738 3.7683C20.9438 2.65378 13.1466 8.48756 12.0982 16.4011C11.6293 19.9388 11.834 23.4516 13.0611 26.853C13.3556 27.6694 13.013 28.4456 12.2732 28.7058C11.6003 28.9423 10.8332 28.6081 10.6222 27.7858C10.1447 25.9241 9.6136 24.0511 9.40715 22.1499C8.9329 17.7827 9.34678 13.5176 11.7619 9.68636C15.3587 3.98012 20.5371 0.920631 27.3078 1.08763C34.8716 1.27413 40.2775 5.04247 43.6842 11.7491C43.7884 11.9541 43.8895 12.1609 43.9469 12.2763Z\" fill=\"#27464E\" stroke=\"#27464E\"><\/path><path d=\"M55.4694 32.8165C56.1134 31.6177 56.7458 30.4124 57.4054 29.2223C57.9043 28.3225 58.8662 28.1198 59.5215 28.7642C60 29.2346 60.0697 29.8077 59.7621 30.3854C58.4897 32.7746 57.2015 35.1554 55.9125 37.5357C55.612 38.0906 55.1355 38.3526 54.503 38.2457C53.8683 38.1385 53.5317 37.7256 53.413 37.1064C52.6678 33.2247 51.9199 29.3434 51.1711 25.4623C51.1111 25.1514 51.0363 24.8432 50.8116 24.5198C50.6015 25.1514 50.3857 25.7812 50.1822 26.4148C49.8296 27.5129 49.4891 28.6149 49.1347 29.7123C48.7839 30.7985 48.4731 31.0259 47.3545 31.0268C44.7154 31.0286 42.0763 31.0403 39.4373 31.0162C38.9117 31.0113 38.6633 31.1471 38.4902 31.6837C37.3354 35.2672 36.136 38.8362 34.9504 42.4098C34.6496 43.3161 34.1864 43.7007 33.4685 43.6444C32.773 43.5899 32.4032 43.1928 32.2109 42.2613C30.7506 35.1872 29.2935 28.1125 27.8342 21.0382C27.7825 20.7873 27.7184 20.5392 27.5144 20.2719C27.2798 21.3069 27.0413 22.3409 26.8118 23.377C26.247 25.9271 25.6883 28.4786 25.123 31.0286C24.917 31.9579 24.5064 32.2875 23.5409 32.2879C16.3777 32.2905 9.21429 32.2905 2.05106 32.2888C1.12516 32.2885 0.518413 31.7826 0.500456 31.0139C0.481225 30.1935 1.07214 29.6608 2.03918 29.6604C8.66042 29.6567 15.2818 29.6502 21.903 29.6724C22.5309 29.6745 22.7823 29.5166 22.9214 28.8669C24.0096 23.7821 25.1462 18.7075 26.2674 13.6298C26.2876 13.5379 26.2967 13.4431 26.3215 13.3526C26.5252 12.6145 27.0066 12.2095 27.662 12.2217C28.3304 12.2342 28.7871 12.637 28.9442 13.3976C30.2542 19.7353 31.5582 26.0742 32.8654 32.4125C33.1724 33.9012 33.4848 35.3888 33.836 37.076C33.9865 36.763 34.0637 36.6381 34.1091 36.5025C34.8551 34.2709 35.5948 32.0371 36.3409 29.8055C36.7446 28.5983 37.0312 28.3935 38.2807 28.393C40.802 28.3925 43.324 28.357 45.8441 28.4145C46.6078 28.4321 46.8848 28.1775 47.0984 27.4739C47.9733 24.5919 48.9185 21.7311 49.8406 18.8633C50.1448 17.9171 50.6436 17.4641 51.3166 17.5094C51.9905 17.5548 52.4397 18.0544 52.6275 19.0295C53.4504 23.3037 54.2635 27.58 55.0816 31.8551C55.1419 32.1696 55.2147 32.4816 55.2816 32.7948C55.3442 32.8021 55.4067 32.8093 55.4694 32.8165Z\" fill=\"#27464E\" stroke=\"#27464E\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCUIDADO APERA\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSeguro de Complicaciones\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4be4c95 e-flex e-con-boxed e-con e-parent\" data-id=\"4be4c95\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-641cf5b e-con-full e-flex e-con e-child\" data-id=\"641cf5b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-639f2a0 e-con-full e-flex e-con e-child\" data-id=\"639f2a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45f46bd elementor-widget elementor-widget-heading\" data-id=\"45f46bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Aspectos clave de\nEl trasplante capilar FUE incluye:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b963275 elementor-widget elementor-widget-heading\" data-id=\"b963275\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Extracci\u00f3n individual de fol\u00edculos:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89aeefb elementor-widget elementor-widget-text-editor\" data-id=\"89aeefb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La FUE consiste en la extracci\u00f3n de fol\u00edculos pilosos individuales de la zona donante, normalmente la parte posterior o los laterales del cuero cabelludo, donde el pelo es gen\u00e9ticamente resistente a la calvicie.<\/p>\n<p>Cada unidad folicular se extrae con un microperforador, dejando cicatrices diminutas y casi invisibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390fad7 elementor-widget elementor-widget-heading\" data-id=\"390fad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Cicatrizaci\u00f3n de la zona donante:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a4ffb6 elementor-widget elementor-widget-text-editor\" data-id=\"0a4ffb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La zona donante cicatriza con peque\u00f1as cicatrices puntiformes, que son menos perceptibles en comparaci\u00f3n con la cicatriz lineal producida por la cirug\u00eda tradicional.<br \/>m\u00e9todos de trasplante capilar como el Trasplante de Unidades Foliculares (FUT).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d374004 elementor-widget elementor-widget-heading\" data-id=\"d374004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Trasplante:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e997d3 elementor-widget elementor-widget-text-editor\" data-id=\"6e997d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una vez extra\u00eddos, los fol\u00edculos pilosos individuales se trasplantan al<br>zona receptora, que es la zona donde el paciente desea m\u00e1s pelo o donde se ha producido la p\u00e9rdida de pelo.<\/p>\n<p>El cirujano crea peque\u00f1as incisiones o puntos receptores<br>para colocar los injertos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c584f94 elementor-widget elementor-widget-heading\" data-id=\"c584f94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Resultados de aspecto natural:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0110523 elementor-widget elementor-widget-text-editor\" data-id=\"0110523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La FUE permite la colocaci\u00f3n precisa de fol\u00edculos pilosos individuales, imitando<br \/>el patr\u00f3n de crecimiento natural y creando un nacimiento del pelo de aspecto m\u00e1s natural.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30afec3 elementor-widget elementor-widget-heading\" data-id=\"30afec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Anestesia local:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed8e66 elementor-widget elementor-widget-text-editor\" data-id=\"4ed8e66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La FUE suele realizarse con anestesia local, lo que hace que el procedimiento sea m\u00e1s c\u00f3modo para el paciente.<br \/>A menudo se realiza en r\u00e9gimen ambulatorio.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-973f822 e-con-full e-flex e-con e-child\" data-id=\"973f822\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-1e6789d e-con-full e-flex e-con e-child\" data-id=\"1e6789d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2906212 elementor-widget elementor-widget-image\" data-id=\"2906212\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"605\" height=\"527\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-34.png\" class=\"attachment-large size-large wp-image-10348\" alt=\"\" srcset=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-34.png 605w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-34-600x523.png 600w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-34-300x261.png 300w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5f84ed e-con-full e-flex e-con e-child\" data-id=\"d5f84ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeae7cf elementor-widget elementor-widget-heading\" data-id=\"eeae7cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Recuperaci\u00f3n:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46bee46 elementor-widget elementor-widget-text-editor\" data-id=\"46bee46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El tiempo de recuperaci\u00f3n de la FUE suele ser m\u00e1s corto que el de los m\u00e9todos tradicionales. Los pacientes pueden experimentar cierto enrojecimiento e hinchaz\u00f3n en las zonas receptora y donante, pero estos efectos secundarios son temporales.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5e3521 elementor-widget elementor-widget-heading\" data-id=\"b5e3521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Resultados:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f194e elementor-widget elementor-widget-text-editor\" data-id=\"66f194e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los resultados finales del trasplante capilar FUE se notan cuando los fol\u00edculos pilosos trasplantados empiezan a crecer. El crecimiento del pelo es un proceso gradual, y pueden pasar varios meses hasta que se vean los resultados completos.<\/p>\n<p>El pelo trasplantado es permanente y se comporta como el pelo natural.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a04c267 elementor-widget elementor-widget-heading\" data-id=\"a04c267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Candidatura:<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceb0b19 elementor-widget elementor-widget-text-editor\" data-id=\"ceb0b19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La FUE es adecuada para las personas que experimentan el sexo masculino o femenino<br \/>calvicie de patr\u00f3n, as\u00ed como a quienes buscan restaurar el cabello en zonas espec\u00edficas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6197100 e-flex e-con-boxed e-con e-parent\" data-id=\"6197100\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ebd7d39 e-con-full e-flex e-con e-child\" data-id=\"ebd7d39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5b67d1a e-con-full e-flex e-con e-child\" data-id=\"5b67d1a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd20448 elementor-widget elementor-widget-image\" data-id=\"cd20448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"317\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-35.png\" class=\"attachment-large size-large wp-image-10349\" alt=\"\" srcset=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-35.png 367w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Image-35-300x259.png 300w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd4dda7 e-con-full e-flex e-con e-child\" data-id=\"bd4dda7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60bab20 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"60bab20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"141\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-158.png\" class=\"attachment-large size-large wp-image-10304\" alt=\"\" srcset=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-158.png 330w, https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-158-300x128.png 300w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67ae657 e-con-full e-flex e-con e-child\" data-id=\"67ae657\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6efcb elementor-widget elementor-widget-heading\" data-id=\"5a6efcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Elegibilidad <br>Lista de control<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2435d3 e-con-full e-flex e-con e-child\" data-id=\"a2435d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af8deaa elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"af8deaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"24\" viewBox=\"0 0 23 24\" fill=\"none\"><path d=\"M0.221 12.044C2.69 13.468 5.157 14.892 7.971 16.515C11.979 9.966 16.734 3.97 22.045 0C17.555 7.11 12.497 15.12 7.414 23.168C5.102 19.826 2.55 16.139 0 12.453C0.074 12.317 0.147 12.18 0.221 12.044Z\" fill=\"#26464E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">18 a\u00f1os o m\u00e1s<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"24\" viewBox=\"0 0 23 24\" fill=\"none\"><path d=\"M0.221 12.044C2.69 13.468 5.157 14.892 7.971 16.515C11.979 9.966 16.734 3.97 22.045 0C17.555 7.11 12.497 15.12 7.414 23.168C5.102 19.826 2.55 16.139 0 12.453C0.074 12.317 0.147 12.18 0.221 12.044Z\" fill=\"#26464E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">En buenas condiciones de salud<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"24\" viewBox=\"0 0 23 24\" fill=\"none\"><path d=\"M0.221 12.044C2.69 13.468 5.157 14.892 7.971 16.515C11.979 9.966 16.734 3.97 22.045 0C17.555 7.11 12.497 15.12 7.414 23.168C5.102 19.826 2.55 16.139 0 12.453C0.074 12.317 0.147 12.18 0.221 12.044Z\" fill=\"#26464E\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Expectativas realistas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96446ec e-flex e-con-boxed e-con e-parent\" data-id=\"96446ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c73475e e-flex e-con-boxed e-con e-child\" data-id=\"c73475e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b756abc elementor-widget elementor-widget-heading\" data-id=\"b756abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nuestro viaje de trasplante capilar FUE con todo incluido<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2301aca e-grid elementor-hidden-mobile e-con-boxed e-con e-child\" data-id=\"2301aca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbc6385 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bbc6385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M9.56687 25.2184C9.92102 24.8658 10.2626 24.522 10.6106 24.1848C10.6442 24.1522 10.7192 24.1458 10.7719 24.152C11.516 24.2403 12.2596 24.3331 13.0033 24.4243C13.3096 24.4618 13.6166 24.4936 13.9219 24.5375C14.0114 24.5504 14.064 24.5284 14.1215 24.4608C15.2018 23.192 16.2847 21.9253 17.3669 20.6581C17.9207 20.0096 18.4746 19.361 19.0283 18.7124C19.0814 18.6502 19.1336 18.5871 19.1984 18.5099C15.6447 17.1563 12.1122 15.8107 8.56641 14.4601C8.60712 14.4148 8.63469 14.3813 8.66523 14.3508C9.08793 13.9276 9.51207 13.506 9.93273 13.0809C9.99338 13.0196 10.048 12.9982 10.1376 13.0108C11.3062 13.1756 12.4753 13.3368 13.6452 13.4915C13.7211 13.5015 13.8169 13.4687 13.8833 13.4251C14.3741 13.1029 14.8491 12.7553 15.3517 12.4533C15.5852 12.3131 15.8627 12.2274 16.1316 12.1693C16.5355 12.0819 16.8102 12.3453 16.7297 12.7473C16.6739 13.0258 16.5493 13.2913 16.4473 13.5597C16.4111 13.6546 16.3506 13.7403 16.289 13.8525C16.482 13.8814 16.6673 13.8904 16.8416 13.9389C17.2329 14.0479 17.5373 13.936 17.8608 13.6927C18.2446 13.4039 18.6809 13.1786 19.1133 12.9639C19.2967 12.8729 19.5285 12.8466 19.7377 12.8488C19.9851 12.8514 20.1309 13.0387 20.1388 13.2886C20.1487 13.6035 20.0178 13.8791 19.888 14.1542C19.8616 14.2103 19.8331 14.2653 19.7975 14.3371C20.1909 14.3922 20.5624 14.445 20.9342 14.4963C21.4872 14.5728 22.0406 14.6459 22.5931 14.726C22.7089 14.7428 22.7905 14.7209 22.8777 14.6335C24.4347 13.0699 26.0249 11.5419 27.7665 10.1811C28.3885 9.69506 29.0244 9.22477 29.7402 8.8841C30.0242 8.7488 30.3301 8.64022 30.6378 8.57762C31.1639 8.47065 31.502 8.82608 31.4211 9.35872C31.3483 9.83876 31.1288 10.26 30.8868 10.6697C30.2836 11.6911 29.5346 12.6044 28.7641 13.5005C27.6801 14.7613 26.5266 15.9572 25.348 17.1292C25.2855 17.1915 25.2461 17.2483 25.2596 17.3446C25.3909 18.2757 25.5181 19.2072 25.6467 20.1387C25.648 20.148 25.6539 20.1566 25.6657 20.1848C25.7124 20.1633 25.7573 20.1389 25.8048 20.1213C26.0379 20.0345 26.2659 19.9237 26.5065 19.8693C26.9475 19.7697 27.2253 20.0341 27.1408 20.4784C27.094 20.7244 27.0126 20.9767 26.8882 21.1923C26.6344 21.6326 26.3397 22.0492 26.0652 22.4776C26.0305 22.5317 25.9908 22.6019 25.997 22.6597C26.0327 22.9858 26.0814 23.3105 26.1267 23.6354C26.1293 23.6539 26.1403 23.6712 26.146 23.6858C26.3695 23.5789 26.5856 23.4634 26.8113 23.3716C26.9546 23.3133 27.1102 23.2752 27.2639 23.2544C27.6446 23.203 27.9067 23.4604 27.826 23.8368C27.7663 24.1152 27.6801 24.4031 27.5357 24.6451C27.2352 25.1485 26.886 25.6227 26.5631 26.113C26.5218 26.1757 26.4904 26.2662 26.4999 26.3378C26.6447 27.435 26.7896 28.5322 26.9536 29.6267C26.9901 29.8706 26.9559 30.0383 26.7661 30.2139C26.3495 30.5992 25.9611 31.015 25.5384 31.4413C24.1813 27.8792 22.8349 24.345 21.4816 20.7928C21.2054 21.0276 20.9445 21.2486 20.6844 21.4707C18.9739 22.9318 17.2638 24.3936 15.5516 25.8527C15.4735 25.9192 15.4412 25.9774 15.4553 26.0868C15.5875 27.1166 15.7107 28.1476 15.8396 29.1778C15.8534 29.2878 15.8344 29.3684 15.7495 29.4507C15.4228 29.7677 15.1054 30.0941 14.7711 30.4303C14.6134 30.1211 14.4648 29.8301 14.3166 29.5389C13.9034 28.7273 13.4925 27.9147 13.0743 27.1057C13.0351 27.0299 12.9617 26.9564 12.8859 26.9174C11.8324 26.3753 10.7757 25.8395 9.71981 25.302C9.67307 25.2781 9.62769 25.2518 9.56687 25.2184Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAeropuerto <br> Transferencia\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19214d0 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"19214d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M12.0673 29.2272C12.0673 29.1879 12.0648 29.1718 12.0677 29.1567C12.4866 26.8929 12.9137 24.6306 13.3215 22.3648C13.4957 21.3968 13.9616 20.6243 14.7821 20.0901C16.0023 19.2957 17.3436 19.1495 18.7432 19.4451C19.6114 19.6284 20.3602 20.0426 20.9751 20.6932C21.2244 20.9569 21.5909 20.9606 21.8344 20.7263C22.0821 20.488 22.0861 20.1144 21.8354 19.8525C21.6868 19.6972 21.5351 19.5427 21.3704 19.4052C20.5075 18.6847 19.501 18.2973 18.3958 18.153C17.0128 17.9724 15.695 18.1846 14.4677 18.8591C13.496 19.393 12.7656 20.1624 12.3901 21.2146C12.2188 21.6947 12.1278 22.2066 12.0328 22.7102C11.5982 25.0137 11.1762 27.3195 10.7472 29.6242C10.6542 30.1241 10.9126 30.4442 11.4236 30.4454C11.9751 30.4468 12.5266 30.4457 13.078 30.4457C14.3175 30.4457 15.557 30.446 16.7965 30.4455C17.0731 30.4454 17.287 30.3326 17.4024 30.0751C17.5865 29.6645 17.2758 29.2282 16.8006 29.2278C15.288 29.2263 13.7754 29.2272 12.2627 29.2272H12.0673Z\" fill=\"white\"><\/path><path d=\"M18.0784 7.16492C18.3097 7.20699 18.5438 7.23751 18.7719 7.29291C20.2886 7.66131 21.485 8.46372 22.2245 9.87156C22.4797 10.3574 22.563 10.8929 22.647 11.4275C22.819 12.5205 22.9927 13.6133 23.1713 14.7052C23.2524 15.2012 22.9981 15.5117 22.4937 15.5152C21.8899 15.5195 21.286 15.5202 20.6824 15.5331C20.5996 15.5349 20.4995 15.5782 20.4388 15.6355C19.5415 16.484 18.4769 16.9046 17.2456 16.8255C16.1833 16.7573 15.2769 16.3093 14.5344 15.5437C14.449 15.4557 14.3681 15.4257 14.2474 15.4321C13.6603 15.4639 13.0727 15.488 12.4851 15.5102C12.1246 15.5238 11.8395 15.239 11.8693 14.8691C11.8946 14.5563 11.9564 14.2462 12.0058 13.9356C12.171 12.8946 12.3347 11.8533 12.5052 10.8132C12.6142 10.1488 12.915 9.56884 13.3434 9.05935C14.2652 7.96317 15.4584 7.36867 16.8705 7.1924C16.906 7.18796 16.9404 7.17429 16.9754 7.16492H18.0784ZM15.806 12.1592C15.6528 12.1453 15.5167 12.1382 15.3822 12.1197C15.0034 12.0675 14.7877 11.7958 14.8315 11.4327C14.8709 11.1062 15.1703 10.8883 15.5254 10.9209C16.6818 11.0273 17.6093 10.6117 18.3044 9.6845C18.5539 9.35156 18.7313 8.98006 18.8454 8.57113C18.4617 8.44384 18.0796 8.39437 17.6901 8.38182C16.3743 8.33925 15.2485 8.76361 14.3519 9.74293C14.024 10.101 13.7858 10.5149 13.7039 10.9986C13.5612 11.8411 13.4331 12.6861 13.2994 13.5302C13.2614 13.7703 13.2256 14.0108 13.1931 14.2235C13.574 14.2235 13.9351 14.2249 14.2962 14.2216C14.3348 14.2212 14.3764 14.1993 14.4113 14.1783C15.1751 13.7186 15.6203 13.0386 15.806 12.1592ZM15.5591 14.846C16.7475 15.975 18.7291 15.872 19.8367 14.4893C19.0134 13.631 18.5247 12.5883 18.2197 11.4875C17.8496 11.6469 17.4932 11.7963 17.1417 11.9566C17.0948 11.978 17.0509 12.0519 17.0433 12.1066C16.9065 13.0896 16.5097 13.9425 15.7917 14.637C15.717 14.7093 15.637 14.7762 15.5591 14.846ZM21.8678 14.2975C21.8609 14.2354 21.857 14.1785 21.848 14.1224C21.7046 13.2217 21.5387 12.324 21.4227 11.4198C21.3023 10.4813 20.8558 9.75717 20.1079 9.20136C20.0632 9.16817 20.0155 9.13913 19.9587 9.10114C19.7829 9.58315 19.567 10.0233 19.2757 10.4245C19.2526 10.4563 19.2507 10.5138 19.2582 10.556C19.3807 11.2408 19.5848 11.8993 19.908 12.5176C20.2739 13.2178 20.7578 13.8126 21.4373 14.2357C21.5739 14.3209 21.7091 14.3237 21.8678 14.2975Z\" fill=\"white\"><\/path><path d=\"M24.6575 22.5575C26.2272 22.5574 27.7971 22.5574 29.3669 22.5575C29.8763 22.5575 30.1007 22.7777 30.1008 23.2814C30.1013 25.4284 30.1011 27.5755 30.1005 29.7226C30.1003 30.1966 29.8485 30.4454 29.3683 30.4454C27.116 30.446 24.8636 30.4477 22.6113 30.4416C22.4457 30.4412 22.3257 30.4922 22.2038 30.5942C21.564 31.13 20.9191 31.6596 20.2767 32.1923C20.1205 32.3219 19.9477 32.4016 19.7414 32.3644C19.4651 32.3146 19.2834 32.1095 19.2524 31.8225C19.2473 31.7757 19.2482 31.7281 19.2482 31.6809C19.2481 28.8671 19.2479 26.0533 19.2483 23.2396C19.2483 22.8791 19.3737 22.6691 19.6523 22.5883C19.7509 22.5598 19.8596 22.5587 19.9638 22.5587C21.5283 22.5569 23.0929 22.5575 24.6575 22.5575ZM20.4795 23.7786V30.4672C20.9022 30.114 21.3081 29.7825 21.7044 29.4401C21.882 29.2866 22.0746 29.224 22.3079 29.2245C24.4345 29.229 26.561 29.2272 28.6876 29.2272H28.88V23.7786H20.4795Z\" fill=\"white\"><\/path><path d=\"M12.0673 29.2272H12.2627C13.7754 29.2272 15.288 29.2263 16.8006 29.2278C17.2758 29.2282 17.5865 29.6645 17.4024 30.0751C17.287 30.3326 17.0731 30.4454 16.7965 30.4455C15.557 30.446 14.3175 30.4457 13.078 30.4457C12.5266 30.4457 11.9751 30.4468 11.4236 30.4454C10.9126 30.4442 10.6542 30.1241 10.7472 29.6242C11.1762 27.3195 11.5982 25.0137 12.0328 22.7102C12.1278 22.2066 12.2188 21.6947 12.3901 21.2146C12.7656 20.1624 13.496 19.393 14.4677 18.8591C15.695 18.1846 17.0128 17.9724 18.3958 18.153C19.501 18.2973 20.5075 18.6847 21.3704 19.4052C21.5351 19.5427 21.6868 19.6972 21.8354 19.8525C22.0861 20.1144 22.0821 20.488 21.8344 20.7263C21.5909 20.9606 21.2244 20.9569 20.9751 20.6932C20.3602 20.0426 19.6114 19.6284 18.7432 19.4451C17.3436 19.1495 16.0023 19.2957 14.7821 20.0901C13.9616 20.6243 13.4957 21.3968 13.3215 22.3648C12.9137 24.6306 12.4866 26.8929 12.0677 29.1567C12.0648 29.1718 12.0673 29.1879 12.0673 29.2272Z\" fill=\"white\"><\/path><path d=\"M24.5755 24.335C23.5066 24.3603 22.6048 25.2734 22.5909 26.3444C22.5862 26.7016 22.8275 26.9737 23.163 26.9897C23.5082 27.0061 23.7799 26.7557 23.8062 26.3966C23.8442 25.8776 24.1339 25.5907 24.6504 25.5373C24.7752 25.5245 24.9118 25.4845 25.0131 25.4141C25.2455 25.2525 25.3126 24.9908 25.2208 24.7308C25.1277 24.4667 24.9004 24.3274 24.5755 24.335ZM24.7532 28.4401C24.7562 28.4399 24.7929 28.4381 24.8296 28.4355C25.8652 28.3635 26.7232 27.4398 26.7139 26.4073C26.7108 26.0593 26.465 25.7938 26.1352 25.7825C25.7888 25.7706 25.5289 26.0121 25.5053 26.3679C25.4703 26.8934 25.1615 27.2015 24.6342 27.2369C24.2869 27.2602 24.0247 27.5434 24.0482 27.8697C24.0744 28.2328 24.3522 28.4699 24.7532 28.4401Z\" fill=\"white\"><\/path><path d=\"M24.5755 24.335C24.9004 24.3274 25.1277 24.4668 25.2209 24.7308C25.3126 24.9908 25.2455 25.2525 25.0131 25.4141C24.9118 25.4846 24.7752 25.5245 24.6504 25.5374C24.1339 25.5907 23.8442 25.8776 23.8062 26.3966C23.7799 26.7557 23.5082 27.0062 23.163 26.9897C22.8275 26.9737 22.5862 26.7016 22.5909 26.3444C22.6048 25.2734 23.5066 24.3603 24.5755 24.335Z\" fill=\"white\"><\/path><path d=\"M24.7534 28.4401C24.3523 28.4698 24.0746 28.2328 24.0483 27.8697C24.0248 27.5434 24.287 27.2602 24.6343 27.2368C25.1617 27.2014 25.4705 26.8933 25.5054 26.3678C25.5291 26.012 25.7889 25.7706 26.1354 25.7824C26.4651 25.7938 26.7109 26.0592 26.714 26.4072C26.7233 27.4397 25.8653 28.3634 24.8297 28.4355C24.793 28.438 24.7563 28.4399 24.7534 28.4401Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTraductor <br><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100c676 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"100c676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M11.4162 14.438H11.3174C10.6263 14.438 9.93524 14.4381 9.24418 14.438C8.58747 14.4379 8.11146 13.9613 8.11142 13.3038C8.11138 12.1884 8.11118 11.073 8.11155 9.95765C8.11192 8.79444 9.00833 7.89642 10.1726 7.8954C11.6517 7.89412 13.1308 7.89507 14.6099 7.89507C18.3028 7.89507 21.9957 7.89157 25.6886 7.89749C26.6216 7.89901 27.2677 8.36902 27.6629 9.19808C27.8024 9.49077 27.858 9.80543 27.8579 10.1302C27.8572 11.7038 27.8575 13.2775 27.8575 14.8512V14.9407H27.9559C28.95 14.9407 29.9442 14.9408 30.9383 14.9406C31.4889 14.9406 31.8886 15.3396 31.8888 15.8902C31.8889 16.4043 31.8891 16.9184 31.8887 17.4324C31.8883 17.9667 31.5042 18.3603 30.9693 18.3758C30.9504 18.3764 30.9317 18.3793 30.9055 18.3818V18.5005C30.9055 21.9534 30.9055 25.4062 30.9054 28.859C30.9054 30.3903 29.8443 31.7066 28.3484 32.0314C26.7142 32.3862 25.0912 31.439 24.5869 29.8326C24.5625 29.7549 24.5292 29.7355 24.4519 29.7355C20.6596 29.7374 16.8673 29.7373 13.075 29.7371C12.2745 29.7371 11.6026 29.1933 11.4398 28.4098C11.4168 28.2991 11.4054 28.1838 11.4053 28.0707C11.4035 26.7419 11.4048 25.4131 11.4057 24.0844C11.4061 23.4249 11.4077 22.7654 11.4084 22.1059C11.4095 20.9008 11.4101 19.6957 11.4114 18.4906C11.4127 17.1692 11.4146 15.8478 11.4162 14.5263V14.438ZM24.4312 21.8613H24.3207C20.9239 21.8613 17.5271 21.8613 14.1303 21.8612C14.0963 21.8612 14.0623 21.8621 14.0285 21.8601C13.9193 21.8536 13.8252 21.8123 13.7552 21.7274C13.6553 21.6062 13.6334 21.4687 13.6982 21.3259C13.7684 21.1711 13.8957 21.1021 14.0655 21.1021C17.4868 21.1028 20.908 21.1026 24.3292 21.1026H24.4298V19.1985H24.3313C20.927 19.1985 17.5228 19.1985 14.1185 19.1984C14.0822 19.1984 14.0456 19.1994 14.0095 19.1958C13.8171 19.1767 13.6749 19.0278 13.6634 18.8352C13.6528 18.6575 13.7769 18.4906 13.9546 18.4505C14.0035 18.4394 14.0556 18.4402 14.1063 18.4401C17.5178 18.4397 20.9293 18.4396 24.3409 18.4396C24.3626 18.4396 24.3851 18.4421 24.406 18.4377C24.4166 18.4355 24.431 18.4214 24.4321 18.4114C24.4333 18.4013 24.4224 18.3837 24.4127 18.3799C24.3978 18.3741 24.3794 18.3769 24.3624 18.3765C23.8426 18.3639 23.45 17.9614 23.4492 17.4395C23.4487 17.1656 23.4491 16.8916 23.4491 16.6176V16.5317H23.3251C20.2676 16.5317 17.2101 16.5317 14.1525 16.5317C14.1113 16.5317 14.07 16.5333 14.0289 16.5309C13.832 16.519 13.6881 16.3825 13.666 16.1881C13.6457 16.0103 13.7605 15.8365 13.936 15.7894C13.9912 15.7745 14.051 15.7718 14.1087 15.7718C17.1759 15.771 20.2431 15.7711 23.3103 15.7711C23.3394 15.7711 23.3687 15.769 23.3976 15.7716C23.442 15.7756 23.4586 15.7594 23.4679 15.7133C23.5654 15.2294 23.9214 14.94 24.4154 14.9399C25.2786 14.9397 26.1418 14.9399 27.005 14.9397C27.0351 14.9397 27.0653 14.9367 27.0995 14.9349V14.8392C27.0995 13.268 27.0993 11.6969 27.0998 10.1257C27.0999 9.94668 27.0694 9.7735 27.0106 9.60505C26.8136 9.04065 26.2966 8.65344 25.7359 8.6534C21.0976 8.65299 16.4592 8.65312 11.8207 8.65328C11.7953 8.65328 11.77 8.65562 11.7459 8.65677C11.7448 8.66585 11.7445 8.67021 11.7445 8.67021C11.7741 8.71435 11.805 8.7577 11.8337 8.8025C12.0884 9.20104 12.1828 9.63546 12.1799 10.109C12.1686 11.9783 12.1735 13.8478 12.1721 15.7171C12.1708 17.5696 12.1693 19.422 12.1678 21.2744C12.167 22.2418 12.1659 23.2092 12.1651 24.1767C12.1639 25.4714 12.1624 26.7661 12.162 28.0609C12.1619 28.5846 12.5509 28.9782 13.0681 28.9783C16.8288 28.9786 20.5894 28.9784 24.3501 28.9784H24.4303V27.1852H24.3315H14.1333C14.0969 27.1852 14.0604 27.1873 14.0242 27.1846C13.877 27.1735 13.7656 27.104 13.702 26.97C13.6373 26.8338 13.6508 26.7003 13.7404 26.5787C13.8291 26.4584 13.9545 26.4256 14.099 26.4257C17.5057 26.427 20.9123 26.4267 24.319 26.4267H24.4304V24.5224H24.3338C20.9199 24.5224 17.5059 24.5224 14.092 24.5224C14.0702 24.5224 14.0483 24.5229 14.0265 24.5221C13.8419 24.5151 13.6921 24.3772 13.6676 24.192C13.6433 24.0084 13.7535 23.8321 13.9313 23.7829C13.9908 23.7664 14.0557 23.7645 14.1182 23.7645C17.5176 23.7637 20.917 23.7638 24.3164 23.7638H24.4312V21.8613ZM25.2071 25.9606C25.2071 26.9254 25.2079 27.8903 25.2066 28.8551C25.2063 29.1216 25.2432 29.3818 25.3284 29.6339C25.8222 31.0958 27.4639 31.7653 28.8249 31.0379C29.6719 30.5851 30.1231 29.8493 30.1309 28.8883C30.1471 26.8812 30.1358 24.8738 30.1357 22.8666C30.1357 22.7661 30.1356 22.7659 30.0382 22.7659C28.4625 22.7659 26.8868 22.7659 25.3111 22.7659C25.2075 22.7659 25.2072 22.7661 25.2072 22.8697C25.2071 23.9001 25.2072 24.9303 25.2071 25.9606ZM30.1423 18.3832H25.1989V21.9901H30.1423V18.3832ZM11.4148 13.6747C11.4148 13.6401 11.4148 13.6116 11.4148 13.583C11.4153 12.3732 11.4151 11.1634 11.417 9.95354C11.4175 9.6713 11.3364 9.41634 11.1636 9.19574C10.8805 8.83426 10.5148 8.62357 10.0452 8.66257C9.35707 8.71973 8.87066 9.26338 8.87037 9.95506C8.86988 11.0704 8.87017 12.1856 8.87029 13.3009C8.87029 13.543 9.00583 13.6781 9.24965 13.6782C9.94305 13.6786 10.6365 13.6786 11.3299 13.6785C11.3559 13.6785 11.3819 13.6763 11.4148 13.6747ZM27.2552 15.701V15.7901C27.2552 15.9089 27.2566 16.0278 27.2548 16.1466C27.2517 16.3603 27.0967 16.5224 26.888 16.5325C26.6906 16.5421 26.5184 16.3947 26.4985 16.1878C26.4876 16.0749 26.4938 15.9602 26.4926 15.8464C26.4922 15.801 26.4925 15.7556 26.4925 15.7056H25.6638C25.6638 15.7365 25.6639 15.7625 25.6638 15.7885C25.6636 15.9121 25.6668 16.0359 25.6623 16.1594C25.6544 16.3757 25.4848 16.5375 25.2767 16.5325C25.0658 16.5274 24.9053 16.3617 24.9035 16.1461C24.9026 16.0297 24.9035 15.9133 24.9034 15.797C24.9033 15.7008 24.9033 15.7007 24.8107 15.7007C24.6797 15.7005 24.5488 15.7004 24.4179 15.7007C24.2671 15.701 24.2121 15.7555 24.212 15.9069C24.2115 16.4016 24.2117 16.8962 24.2116 17.3908C24.2116 17.5677 24.2594 17.6159 24.4349 17.6159C26.1758 17.6159 27.9167 17.6159 29.6576 17.6159C30.0868 17.6159 30.516 17.6162 30.9452 17.6156C31.0647 17.6155 31.1292 17.5549 31.1294 17.4397C31.1303 16.9184 31.1303 16.3971 31.1294 15.8758C31.1292 15.7666 31.0666 15.703 30.958 15.7013C30.8053 15.699 30.6525 15.7025 30.4998 15.6997C30.4473 15.6987 30.4339 15.7188 30.4349 15.7679C30.4375 15.8988 30.4373 16.0298 30.4353 16.1607C30.4324 16.3578 30.2859 16.5117 30.0853 16.5313C29.9041 16.5491 29.7286 16.4214 29.6882 16.2383C29.6778 16.1915 29.6765 16.1422 29.6759 16.094C29.6742 15.9661 29.6753 15.8383 29.6753 15.7078H28.8464C28.8464 15.8552 28.8475 15.9955 28.8461 16.1358C28.8438 16.3656 28.6776 16.5359 28.4609 16.5326C28.2461 16.5293 28.0873 16.3605 28.0861 16.1335C28.0855 16.0098 28.0856 15.8862 28.0862 15.7625C28.0863 15.7285 28.0857 15.7003 28.0384 15.7005C27.7817 15.7016 27.525 15.701 27.2552 15.701Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><path d=\"M19.6281 10.4482C21.4801 10.4482 23.3321 10.4482 25.1842 10.4483C25.3866 10.4483 25.5291 10.5428 25.5834 10.7119C25.6608 10.9525 25.4881 11.195 25.2301 11.2075C25.2107 11.2084 25.1913 11.2078 25.1719 11.2078C21.4799 11.2078 17.7879 11.2079 14.0959 11.2072C14.043 11.2072 13.9884 11.204 13.9377 11.1906C13.769 11.1461 13.6524 10.9784 13.665 10.8069C13.6787 10.6204 13.8117 10.4756 13.9921 10.4528C14.028 10.4482 14.0646 10.4484 14.1009 10.4484C15.9433 10.4482 17.7857 10.4482 19.6281 10.4482Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><path d=\"M19.6375 13.1115C21.4871 13.1115 23.3368 13.1114 25.1864 13.1115C25.3882 13.1115 25.5315 13.2075 25.5842 13.3768C25.6589 13.6163 25.4908 13.8542 25.2355 13.87C25.2113 13.8716 25.1869 13.8707 25.1627 13.8707C21.4828 13.8708 17.803 13.8708 14.123 13.8705C14.0747 13.8705 14.0257 13.8705 13.9783 13.8624C13.7918 13.831 13.6586 13.6679 13.6642 13.4823C13.6703 13.2872 13.8153 13.1316 14.0087 13.1136C14.0327 13.1113 14.0571 13.1115 14.0813 13.1115C15.9333 13.1114 17.7855 13.1115 19.6375 13.1115Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPrueba preoperatoria <br><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e92589c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e92589c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M10.6055 17.9271C10.6693 17.7327 10.7515 17.5518 10.9152 17.4153C11.0867 17.2725 11.2904 17.2328 11.5011 17.2024C13.2387 16.9515 14.9759 16.6984 16.7138 16.4499C16.7997 16.4376 16.8199 16.3829 16.8486 16.3247C17.5216 14.9617 18.1944 13.5986 18.8671 12.2354C18.9795 12.0077 19.0936 11.7807 19.2028 11.5514C19.3641 11.2127 19.6271 11.0201 20.0041 11.0212C20.377 11.0224 20.633 11.2191 20.7957 11.5495C21.5313 13.0429 22.2684 14.5355 23.0049 16.0284C23.0412 16.102 23.0886 16.1722 23.112 16.2496C23.1601 16.4084 23.2695 16.4501 23.4227 16.4717C24.7081 16.6527 25.9924 16.8417 27.277 17.0287C27.7567 17.0986 28.2389 17.155 28.7151 17.2438C29.3414 17.3606 29.6081 18.1228 29.1998 18.6131C29.0601 18.7807 28.8939 18.9266 28.7371 19.0796C27.5824 20.2053 26.4276 21.3309 25.2705 22.4541C25.2066 22.5161 25.1918 22.5697 25.207 22.6579C25.5142 24.4298 25.8186 26.2022 26.1193 27.9752C26.175 28.3037 26.0624 28.5807 25.8018 28.7855C25.5531 28.9808 25.2641 29.0397 24.9744 28.9077C24.6085 28.7411 24.2564 28.5441 23.9001 28.3571C22.63 27.6905 21.3601 27.0234 20.0921 26.3529C20.0184 26.3139 19.967 26.3224 19.8997 26.3578C18.3264 27.1869 16.7522 28.0142 15.1782 28.8418C14.7216 29.0819 14.2529 28.9724 13.9963 28.564C13.8858 28.3882 13.8429 28.1938 13.8774 27.9905C14.0966 26.6993 14.3197 25.4087 14.5415 24.118C14.6282 23.6133 14.7169 23.1088 14.798 22.6032C14.8046 22.5618 14.7706 22.501 14.737 22.468C14.0749 21.8184 13.41 21.1715 12.7455 20.5242C12.1596 19.9533 11.5761 19.3799 10.986 18.8133C10.8068 18.6413 10.6647 18.4531 10.6055 18.209V17.9271Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9xito <br> Cirug\u00eda\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3440459 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3440459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M23.5591 6.05908C23.9071 6.15114 24.234 6.28429 24.4641 6.57695C24.836 7.05013 24.9342 7.57463 24.6791 8.1271C24.4159 8.69691 23.9458 8.98911 23.3187 8.99124C21.3932 8.99777 19.4677 8.99456 17.5422 8.99302C17.1701 8.99271 16.7928 9.0206 16.4273 8.96932C15.7261 8.87098 15.2223 8.29844 15.1834 7.62099C15.1427 6.91258 15.5583 6.3295 16.2557 6.11637C16.3164 6.0978 16.3768 6.07821 16.4373 6.05908H23.5591ZM19.6865 7.51315C19.685 7.02632 19.4037 6.71736 18.9607 6.71593C18.5181 6.7145 18.2074 7.03432 18.2054 7.49343C18.2031 7.99321 18.4821 8.3056 18.9324 8.30762C19.3824 8.30964 19.6879 7.98784 19.6865 7.51315ZM17.0389 6.74934C16.9788 6.74473 16.9438 6.74473 16.9097 6.73897C16.7348 6.70937 16.6778 6.77556 16.6867 6.95608C16.7026 7.27489 16.6911 7.59505 16.6911 7.91466V8.27302H17.0486V7.6447H17.6262V8.27473H17.9609V6.75426H17.616V7.31528H17.0389V6.74934ZM22.0878 7.99011H21.4755V7.62183H22.0202V7.34953H21.4729V7.02699H22.0517V6.75234H21.1259V8.27065H22.0878V7.99011ZM20.1563 7.02922V8.26981H20.5073V7.02262H20.9181V6.75238H19.7536V7.02922H20.1563ZM22.6781 7.98284V6.75046H22.3467V8.27358H23.291V7.98284H22.6781Z\" fill=\"white\"><\/path><path d=\"M28.9198 12.583H28.3784V31.9947H29.4163V33.9406H10.584V32.0011H11.6188V12.5893H11.0775V9.45215H28.9198V12.583ZM17.1116 31.9886H22.8929V26.2473H23.2799H23.6759C23.5986 24.7906 22.9862 23.6697 21.696 23.0078C20.2754 22.2791 18.8935 22.4415 17.6504 23.4315C16.7644 24.1372 16.334 25.0939 16.3217 26.2527H17.1116V31.9886ZM18.5234 21.5205H21.4749V18.5787H18.5234V21.5205ZM21.4762 13.6245H18.5278V16.5587H21.4762V13.6245ZM16.6935 18.5848H13.746V21.5254H16.6935V18.5848ZM26.2569 18.5843H23.3035V21.52H26.2569V18.5843ZM13.7426 16.5547C13.7761 16.5612 13.7979 16.5691 13.8198 16.5692C14.739 16.5703 15.6582 16.5687 16.5773 16.5732C16.7136 16.5738 16.7061 16.4954 16.706 16.4038C16.7051 15.5322 16.7021 14.6607 16.7087 13.7892C16.7098 13.6418 16.6634 13.6042 16.521 13.6052C15.6542 13.611 14.7874 13.6079 13.9206 13.6086C13.8643 13.6086 13.808 13.6152 13.7426 13.6192V16.5547ZM26.2545 13.6249C26.2215 13.6184 26.1996 13.6104 26.1778 13.6103C25.2586 13.6092 24.3394 13.6108 23.4202 13.6063C23.2843 13.6056 23.2911 13.6833 23.2912 13.7753C23.2922 14.6469 23.2951 15.5185 23.2886 16.39C23.2875 16.5369 23.3331 16.5752 23.4759 16.5743C24.3427 16.5684 25.2095 16.5715 26.0764 16.5709C26.1327 16.5708 26.189 16.5643 26.2545 16.5602V13.6249Z\" fill=\"white\"><\/path><path d=\"M18.5625 7.53296C18.5754 7.45503 18.5829 7.39178 18.5966 7.32995C18.6451 7.10949 18.7734 6.99191 18.9566 6.99672C19.1256 7.00109 19.2745 7.12757 19.2945 7.33211C19.3098 7.48848 19.2946 7.65521 19.2546 7.80732C19.2169 7.95035 19.0972 8.03159 18.9357 8.02488C18.7769 8.01832 18.6752 7.9337 18.6253 7.78941C18.5954 7.70287 18.5811 7.61088 18.5625 7.53296Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLujo <br> Hotel\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04bc63b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"04bc63b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M26.4052 28.4863C25.8149 28.3145 25.2908 28.1184 24.7491 28.0157C24.1063 27.8937 23.4751 28.0282 22.894 28.3304C22.4471 28.5629 22.0259 28.5589 21.5761 28.3306C20.5137 27.7914 19.4421 27.8061 18.3827 28.3475C17.998 28.5441 17.6159 28.5793 17.2265 28.3852C16.1069 27.8271 14.9992 27.8417 13.8993 28.4399C13.8238 28.481 13.7417 28.5099 13.6136 28.5659C13.2597 27.9005 12.8972 27.2512 12.5648 26.5868C12.0455 25.5486 11.6359 24.4672 11.3598 23.3373C11.3187 23.1688 11.2879 23.0416 11.4985 22.9297C13.9092 21.6484 16.421 20.6318 19.077 19.982C19.6806 19.8343 20.2806 19.826 20.8836 19.9725C23.5599 20.623 26.0925 21.6415 28.5157 22.9431C28.6531 23.0168 28.701 23.0895 28.6647 23.2402C28.2072 25.1394 27.3736 26.8738 26.4052 28.4863Z\" fill=\"white\"><\/path><path d=\"M28.9061 22.2068C28.156 21.8391 27.4921 21.5015 26.8181 21.1855C24.9823 20.3248 23.0729 19.6712 21.1066 19.1807C20.3475 18.9913 19.5919 19.0024 18.8341 19.1929C16.329 19.8226 13.9315 20.7324 11.6472 21.9397C11.4853 22.0253 11.3177 22.1002 11.0702 22.2201C11.0238 21.2592 10.9768 20.3616 10.9398 19.4637C10.9305 19.2378 11.0918 19.126 11.2733 19.0221C13.4724 17.7641 15.8029 16.8653 18.2979 16.3935C19.0888 16.244 19.8645 16.0204 20.6829 16.175C23.3591 16.6805 25.9496 17.4295 28.3247 18.8099C29.0963 19.2583 29.0942 19.0388 29.0551 20.1001C29.0299 20.7833 28.9602 21.4647 28.9061 22.2068Z\" fill=\"white\"><\/path><path d=\"M21.6998 8.99516H20.3816V11.8796C20.5413 11.8796 20.6538 11.8815 20.7661 11.8794C22.8137 11.8413 24.8475 12.0158 26.8772 12.2654C27.1132 12.2944 27.215 12.3901 27.1962 12.6213C27.1954 12.631 27.1962 12.6409 27.1964 12.6507C27.2087 13.2634 27.2087 13.2634 26.5846 13.3142V17.2469C26.238 17.1142 25.9437 16.9989 25.6476 16.8886C23.9518 16.2574 22.2205 15.7539 20.4355 15.445C19.8383 15.3417 19.2632 15.4869 18.6882 15.6111C16.9963 15.9765 15.3468 16.4822 13.7395 17.1252C13.6509 17.1606 13.5596 17.1887 13.427 17.2351V13.355C13.3735 13.3221 13.3584 13.3068 13.3408 13.3028C13.1755 13.2654 12.8906 13.2663 12.8665 13.1873C12.7955 12.9537 12.8056 12.6864 12.8341 12.4381C12.8418 12.3711 13.0235 12.2885 13.1333 12.2742C15.1611 12.0096 17.1956 11.8405 19.2432 11.8803C19.3479 11.8823 19.4526 11.8805 19.5813 11.8805C19.612 10.9042 19.6416 9.96498 19.6718 9.00182H18.2999C18.2999 9.45475 18.3013 9.90338 18.2995 10.3521C18.298 10.7111 18.2288 10.7844 17.9038 10.7828C17.5879 10.7811 17.5227 10.706 17.5209 10.3388C17.5188 9.91641 17.5178 9.49401 17.5151 9.07162C17.515 9.05352 17.5033 9.03548 17.519 9.08058C17.3429 8.97853 17.2111 8.90213 17.0791 8.82573C17.2015 8.7564 17.3238 8.68707 17.5212 8.57506C17.5212 8.23809 17.5204 7.81092 17.5215 7.38376C17.5225 7.01029 17.6018 6.94049 17.9727 6.95128C18.209 6.95818 18.3052 7.07025 18.3014 7.3024C18.2946 7.72267 18.2995 8.14306 18.2995 8.60513C18.7736 8.56917 19.2169 8.53562 19.741 8.49589C19.741 7.99037 19.7352 7.5019 19.746 7.01377C19.7481 6.91774 19.787 6.7894 19.8557 6.73457C20.0156 6.607 20.2427 6.7239 20.2475 6.93713C20.259 7.44571 20.2512 7.95471 20.2512 8.49336C20.7689 8.5345 21.2134 8.56988 21.6997 8.60855C21.6997 8.17248 21.6982 7.76294 21.7002 7.3534C21.7019 7.01666 21.7661 6.95323 22.0918 6.95393C22.4174 6.9547 22.4774 7.01578 22.4788 7.35976C22.4805 7.7897 22.4792 8.21964 22.4792 8.58426C22.6593 8.68666 22.7874 8.75953 22.9155 8.83245C22.7905 8.90408 22.6656 8.97576 22.4793 9.08258C22.4793 9.45923 22.4805 9.91817 22.4789 10.3771C22.4777 10.7037 22.3989 10.7837 22.0859 10.7858C21.7814 10.7878 21.7018 10.705 21.7003 10.3725C21.6982 9.92242 21.6998 9.47232 21.6998 8.99516ZM18.4506 14.5683V14.5702H18.9808C19.7592 14.5702 19.7806 14.5475 19.7519 13.7528C19.7409 13.4501 19.6423 13.3454 19.3415 13.3423C18.8703 13.3373 18.3989 13.3497 17.9279 13.339C17.0774 13.3197 17.12 13.3728 17.127 14.186C17.1291 14.434 17.251 14.5695 17.5082 14.5686C17.8223 14.5675 18.1365 14.5683 18.4506 14.5683ZM21.5635 13.3409C21.377 13.3409 21.1905 13.3408 21.0039 13.3409C20.2442 13.3411 20.2192 13.3676 20.2454 14.1428C20.2562 14.4619 20.3549 14.566 20.6733 14.5692C21.1445 14.5739 21.6161 14.5599 22.0869 14.5725C22.9096 14.5944 22.8856 14.5291 22.8734 13.707C22.8733 13.6972 22.8724 13.6874 22.8713 13.6776C22.8475 13.4592 22.7343 13.3398 22.506 13.3412C22.1919 13.3431 21.8777 13.3417 21.5635 13.3409ZM15.3183 13.3424V13.3409C15.1415 13.3409 14.9647 13.3408 14.7879 13.341C14.0012 13.3419 13.9804 13.3635 14.0069 14.1487C14.0177 14.4675 14.1144 14.5663 14.4382 14.569C14.8998 14.573 15.3617 14.5588 15.8229 14.5726C16.7128 14.5991 16.6356 14.4992 16.6311 13.7018C16.6298 13.4633 16.5006 13.3425 16.2611 13.3424C15.9468 13.3423 15.6326 13.3424 15.3183 13.3424ZM24.6718 14.5702C24.8485 14.5702 25.0254 14.5649 25.202 14.571C26.0962 14.6023 25.9868 14.4771 25.9889 13.7135C25.9895 13.4703 25.864 13.3364 25.6011 13.3402C25.12 13.3473 24.6388 13.3409 24.1577 13.3412C23.355 13.3417 23.3364 13.3615 23.3673 14.1673C23.3786 14.4616 23.4815 14.5639 23.7881 14.569C24.0825 14.5738 24.3772 14.57 24.6718 14.5702Z\" fill=\"white\"><\/path><path d=\"M33.0085 29.1426C32.4361 29.3631 31.8742 29.6194 31.2878 29.7924C30.8352 29.9258 30.3695 29.817 29.9421 29.6113C29.2346 29.2708 28.5484 29.2894 27.8599 29.6773C27.0682 30.1233 26.2478 30.1436 25.4331 29.7453C24.7633 29.4177 24.1227 29.428 23.462 29.7782C22.6445 30.2112 21.8019 30.224 20.9746 29.8008C20.3204 29.4662 19.6895 29.4639 19.0319 29.7987C18.1962 30.224 17.345 30.2102 16.5168 29.7684C15.8783 29.4279 15.2499 29.4111 14.6011 29.7314C13.7655 30.144 12.9312 30.1188 12.1188 29.6671C11.461 29.3014 10.8017 29.2695 10.1175 29.5848C9.3101 29.957 8.52379 29.9146 7.75364 29.4585C7.51088 29.3148 7.24046 29.2179 6.99121 29.0614C7.28485 29.1478 7.58799 29.2108 7.87019 29.3252C8.58216 29.614 9.26288 29.5899 9.93258 29.2031C10.7215 28.7476 11.5322 28.717 12.3557 29.1093C13.014 29.423 13.6581 29.4106 14.3022 29.0583C15.1271 28.6071 15.9728 28.5837 16.814 29.0055C17.4609 29.3299 18.0865 29.329 18.729 28.9938C19.582 28.5487 20.4454 28.5569 21.2973 29.0041C21.9188 29.3303 22.5314 29.3306 23.1576 29.0154C23.9972 28.5927 24.8442 28.598 25.6709 29.0447C26.3359 29.4041 26.9887 29.4201 27.6706 29.0956C28.4707 28.715 29.2728 28.7438 30.0404 29.188C30.7414 29.5936 31.4453 29.6191 32.1835 29.3045C32.4326 29.1982 32.7042 29.1446 32.9655 29.0669C32.9799 29.0921 32.9942 29.1174 33.0085 29.1426Z\" fill=\"white\"><\/path><path d=\"M32.2619 30.9265C32.0474 31.0195 31.8267 31.1008 31.6194 31.2078C30.9038 31.5771 30.1718 31.6158 29.4289 31.3164C28.7496 31.0426 28.0967 31.0698 27.439 31.3945C26.7132 31.7529 25.9581 31.7759 25.2154 31.458C24.5392 31.1685 23.8957 31.1772 23.2282 31.4913C22.5198 31.8245 21.7707 31.8503 21.0561 31.5325C20.3435 31.2157 19.6783 31.2019 18.9603 31.5263C18.2071 31.8667 17.426 31.8096 16.6778 31.4552C16.082 31.1729 15.4891 31.1631 14.8853 31.4223C14.0809 31.7675 13.2816 31.7574 12.4945 31.3667C11.8768 31.0601 11.2527 31.0455 10.6158 31.3021C9.84189 31.6139 9.08536 31.5836 8.34333 31.1887C8.14631 31.0839 7.9319 31.0118 7.73535 30.8789C7.9658 30.9413 8.20379 30.9842 8.42533 31.0697C9.11548 31.3361 9.78129 31.3141 10.4449 30.9761C11.1979 30.5926 11.9701 30.5761 12.7492 30.9069C13.3731 31.1718 13.9848 31.1517 14.598 30.8547C15.3756 30.4782 16.1735 30.461 16.9623 30.8117C17.5975 31.0942 18.2057 31.0792 18.8358 30.7891C19.5975 30.4383 20.3839 30.4341 21.1468 30.7834C21.7974 31.0813 22.4204 31.088 23.0764 30.7965C23.8224 30.465 24.5922 30.4705 25.3306 30.8255C26.0043 31.1494 26.6569 31.1642 27.346 30.8732C28.0818 30.5626 28.8263 30.6031 29.5387 30.968C30.2002 31.3068 30.8662 31.3409 31.5583 31.0752C31.7826 30.9891 32.0215 30.9407 32.2537 30.8751C32.2565 30.8923 32.2592 30.9093 32.2619 30.9265Z\" fill=\"white\"><\/path><path d=\"M30.9762 32.5791C30.763 32.675 30.547 32.7652 30.3371 32.8677C29.7492 33.1546 29.1389 33.1963 28.539 32.9554C27.8755 32.6892 27.2565 32.7027 26.6111 33.0212C25.9932 33.3261 25.3307 33.3355 24.6973 33.0626C24.0779 32.7957 23.4941 32.8008 22.8823 33.0868C22.2282 33.3925 21.5438 33.3945 20.8841 33.0995C20.2894 32.8336 19.7203 32.8272 19.1244 33.0947C18.4439 33.4002 17.7445 33.3867 17.0706 33.0707C16.4995 32.8029 15.9462 32.7885 15.3666 33.0371C14.6812 33.3312 13.9862 33.3216 13.3151 32.9902C12.7212 32.6968 12.135 32.685 11.5248 32.9323C10.8698 33.1977 10.2224 33.1575 9.59145 32.8332C9.40976 32.7399 9.21792 32.6662 9.03906 32.5428C9.22853 32.5934 9.42502 32.6262 9.6063 32.6978C10.2484 32.9511 10.8648 32.9154 11.4809 32.6027C12.1106 32.2832 12.7706 32.2635 13.4186 32.5333C14.0182 32.783 14.5905 32.7885 15.1793 32.5049C15.8725 32.1709 16.5841 32.1659 17.287 32.4794C17.8435 32.7275 18.3834 32.7172 18.9354 32.4623C19.6224 32.1451 20.329 32.1335 21.0168 32.4452C21.6111 32.7146 22.1739 32.7168 22.7747 32.4535C23.4429 32.1605 24.136 32.172 24.7992 32.4952C25.385 32.7807 25.9576 32.7917 26.5593 32.5402C27.2272 32.2611 27.9008 32.2843 28.5516 32.6157C29.1472 32.9189 29.7502 32.9451 30.373 32.7047C30.562 32.6318 30.7637 32.5918 30.9596 32.5367C30.9651 32.5509 30.9707 32.5649 30.9762 32.5791Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBarco <br> Visita\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-897ef17 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"897ef17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M33.6918 17.0315C33.6414 17.3114 33.611 17.5967 33.5376 17.8705C33.0279 19.7729 31.8645 21.0941 30.0156 21.7981C29.9723 21.8146 29.9298 21.8334 29.8666 21.8595C30.0265 22.0191 30.1794 22.1624 30.3217 22.3155C30.6411 22.6593 30.9537 23.0095 31.2743 23.3522C31.3052 23.3853 31.3753 23.4047 31.4217 23.397C31.8383 23.3273 32.2547 23.2549 32.6692 23.1738C33.1298 23.0837 33.4688 23.3642 33.4401 23.8347C33.365 25.0641 32.9451 26.1726 32.2384 27.1743C31.4268 28.3247 30.3656 29.1887 29.1324 29.8515C28.456 30.2151 27.7428 30.4889 27.0105 30.7167C27.0071 30.7374 27.0002 30.7532 27.003 30.767C27.0966 31.2272 26.8422 31.5492 26.3713 31.5569C26.0435 31.5622 25.7156 31.558 25.3877 31.558C23.8436 31.558 22.2995 31.5614 20.7555 31.5528C20.5993 31.552 20.4233 31.5124 20.292 31.4326C20.0321 31.2747 20.0065 31.0096 20.0671 30.7336C19.7162 30.608 19.3653 30.4942 19.0234 30.358C17.432 29.724 16.0566 28.7892 15.0037 27.42C14.1806 26.3497 13.7045 25.1425 13.6213 23.7886C13.5974 23.4003 13.9498 23.0904 14.3348 23.1595C14.7661 23.2369 15.1974 23.3154 15.6278 23.3978C15.7164 23.4148 15.7679 23.3982 15.8241 23.3193C15.9371 23.1608 16.0578 23.0046 16.195 22.8671C18.029 21.0292 19.8655 19.1939 21.7032 17.3597C22.5311 16.5335 23.7222 16.3436 24.7215 16.8726C24.9937 17.0166 25.1237 17.2983 25.0463 17.576C24.9696 17.851 24.7091 18.0409 24.4257 18.0142C24.3336 18.0055 24.2416 17.9698 24.1549 17.9337C23.509 17.6644 23.0025 17.7621 22.5076 18.2569C20.7688 19.9955 19.0306 21.7347 17.2899 23.4714C17.2508 23.5103 17.185 23.5224 17.1316 23.547C17.1517 23.5716 17.1718 23.5963 17.1919 23.621C21.4204 24.133 25.6486 24.133 29.9023 23.6176C29.8649 23.5713 29.848 23.546 29.827 23.525C29.3743 23.0728 28.9223 22.6199 28.4665 22.171C28.4256 22.1307 28.3614 22.1004 28.3044 22.0926C27.9336 22.0414 27.5623 21.992 27.1898 21.9577C27.1324 21.9524 27.053 22.0153 27.0086 22.0677C26.8009 22.3126 26.5051 22.3845 26.243 22.2424C25.8927 22.0525 25.8009 21.6412 26.0566 21.3281C26.1529 21.2102 26.1466 21.1298 26.089 20.9974C25.4373 19.499 25.4927 18.0085 26.2221 16.5594C26.9743 15.065 28.167 14.0782 29.7967 13.6552C30.7296 13.4131 31.6595 13.4535 32.5762 13.762C32.7619 13.8244 32.8942 13.9378 32.9932 14.1049C33.3708 14.7421 33.5987 15.4269 33.664 16.1654C33.6672 16.2008 33.6823 16.2351 33.6918 16.27V17.0315ZM14.9352 24.5097C15.1437 25.4356 15.5649 26.231 16.1623 26.9337C17.172 28.1211 18.4546 28.9037 19.914 29.406C21.5552 29.9708 23.2425 30.1218 24.963 29.909C26.3736 29.7346 27.7054 29.3174 28.9291 28.5849C30.0073 27.9394 30.9123 27.1137 31.5463 26.0141C31.8163 25.546 32.0142 25.0502 32.131 24.51C26.3967 25.449 20.6761 25.4494 14.9352 24.5097ZM27.0356 20.1015C27.222 19.8713 27.3946 19.6591 27.5663 19.4461C28.1831 18.6807 28.7991 17.9146 29.4165 17.1496C29.6111 16.9084 29.8717 16.8307 30.1348 16.9306C30.5333 17.0818 30.6429 17.5435 30.3592 17.8982C29.7418 18.67 29.1212 19.4392 28.5021 20.2096C28.3316 20.4217 28.1619 20.6344 27.9918 20.8469C27.9972 20.863 28.0027 20.8791 28.0081 20.8952C28.3421 20.8704 28.6825 20.8786 29.009 20.8152C30.3238 20.5595 31.3034 19.8196 31.9464 18.6559C32.6024 17.4689 32.6836 16.2409 32.1065 14.9909C32.0596 14.8893 31.992 14.8382 31.8864 14.8136C31.1183 14.6353 30.3571 14.6636 29.6307 14.968C27.9542 15.6707 27.0259 16.9421 26.8586 18.7523C26.8172 19.1997 26.8791 19.6469 27.0356 20.1015Z\" fill=\"white\"><\/path><path d=\"M14.4676 9.87964C14.4748 9.72354 14.4841 9.56647 14.4889 9.40925C14.5128 8.63242 14.5358 7.85553 14.5587 7.07863C14.5698 6.70424 14.8283 6.43199 15.1652 6.44063C15.5203 6.44978 15.7737 6.72133 15.7628 7.10395C15.7192 8.64189 15.6697 10.1797 15.6234 11.7176C15.6193 11.8542 15.6228 11.9911 15.6228 12.1412C16.1205 12.0544 16.6097 11.9445 17.1039 11.7003C16.9969 11.6474 16.9211 11.6081 16.8437 11.5721C16.5293 11.426 16.3994 11.0987 16.5289 10.7769C16.646 10.4861 16.9843 10.3431 17.2958 10.4609C17.6102 10.5797 17.8972 10.7441 18.1296 10.9935C18.3436 11.2232 18.4284 11.4958 18.4185 11.8063C18.3575 13.7034 18.2987 15.6006 18.2393 17.4978C18.2284 17.8466 18.2177 18.1954 18.207 18.5442C18.1951 18.9301 17.94 19.1978 17.593 19.1887C17.2367 19.1793 16.9915 18.9117 17.0024 18.5241C17.0363 17.3138 17.0761 16.1037 17.1132 14.8935C17.1314 14.3016 17.1489 13.7097 17.166 13.1178C17.167 13.0823 17.1615 13.0466 17.1597 13.0214C16.6322 13.147 16.1103 13.2713 15.5443 13.406C15.5443 13.6818 15.5519 13.9772 15.5431 14.2722C15.4734 16.6081 15.401 18.9439 15.3282 21.2797C15.3187 21.5855 15.1744 21.7999 14.9305 21.8855C14.5073 22.034 14.1121 21.7272 14.1246 21.2538C14.1435 20.535 14.1678 19.8163 14.1899 19.0976C14.2392 17.491 14.2895 15.8845 14.3368 14.2779C14.3442 14.0258 14.3379 13.7732 14.3379 13.5006C12.735 13.5613 11.1308 13.5127 9.58964 13.0057C9.58964 13.3586 9.58068 13.7057 9.5912 14.0522C9.63675 15.5531 9.688 17.0538 9.73724 18.5545C9.80725 20.6894 9.87781 22.8242 9.94713 24.9591C9.97512 25.8205 10.0039 26.6818 10.0237 27.5434C10.027 27.6869 10.0659 27.7544 10.2105 27.7982C11.0693 28.0585 11.9509 28.1309 12.8413 28.1413C13.0528 28.1438 13.2643 28.1397 13.4758 28.1422C13.8462 28.1467 14.1145 28.4016 14.1159 28.7468C14.1173 29.0916 13.8505 29.3409 13.4755 29.3476C12.384 29.3669 11.2981 29.3233 10.2325 29.056C9.85233 28.9605 9.48191 28.84 9.15117 28.6201C8.95189 28.4876 8.84855 28.3104 8.84089 28.066C8.77056 25.8148 8.6967 23.5637 8.62284 21.3126C8.54307 18.8818 8.46202 16.451 8.38194 14.0203C8.35754 13.2805 8.33934 12.5404 8.30881 11.8009C8.29184 11.3895 8.45681 11.0766 8.77659 10.8319C9.24146 10.476 9.78594 10.3092 10.3431 10.1786C11.5408 9.89801 12.7581 9.84359 13.9824 9.88082C14.1251 9.88517 14.2678 9.89026 14.4105 9.89385C14.4251 9.89423 14.4399 9.88679 14.4676 9.87964ZM14.4094 11.0993C12.7932 11.0488 11.1853 11.0489 9.65099 11.6931C11.1755 12.3437 12.7773 12.3379 14.4094 12.2977V11.0993Z\" fill=\"white\"><\/path><path d=\"M22.2021 13.6726C22.2156 13.0225 22.4231 12.476 22.6676 11.9406C22.9612 11.2976 23.264 10.6587 23.5515 10.013C23.6236 9.8511 23.6619 9.67196 23.699 9.49723C23.7804 9.11382 23.6385 8.8307 23.3013 8.63206C22.9811 8.44345 22.8766 8.12449 23.0209 7.82168C23.1696 7.50943 23.5549 7.38944 23.8553 7.56175C24.7729 8.08802 25.1113 8.93964 24.8286 9.99508C24.6566 10.6377 24.3451 11.2201 24.0641 11.8165C23.8754 12.2172 23.695 12.6224 23.5307 13.0335C23.4634 13.202 23.4314 13.3896 23.4127 13.5715C23.3808 13.8815 23.5224 14.1127 23.7908 14.2648C23.9525 14.3565 24.0869 14.4703 24.137 14.6571C24.2012 14.8966 24.1512 15.1117 23.9659 15.279C23.7645 15.4607 23.5299 15.4902 23.2897 15.3651C22.5867 14.9987 22.2126 14.4239 22.2021 13.6726Z\" fill=\"white\"><\/path><path d=\"M13.1605 31.5329C11.9022 31.532 10.6461 31.4809 9.43511 31.0885C9.22172 31.0193 9.01529 30.9156 8.82208 30.8003C8.52447 30.6228 8.44743 30.2607 8.62368 29.9725C8.79676 29.6894 9.14106 29.6001 9.43816 29.7728C9.89261 30.037 10.4001 30.1171 10.9052 30.1921C12.0964 30.3691 13.2948 30.3921 14.4935 30.2909C14.9818 30.2496 15.4708 30.1854 15.9508 30.0886C16.2444 30.0294 16.6317 30.1808 16.7118 30.5585C16.7828 30.8934 16.5587 31.2229 16.1842 31.2768C15.4952 31.3759 14.8036 31.4604 14.1109 31.5277C13.7969 31.5582 13.4775 31.5329 13.1605 31.5329Z\" fill=\"white\"><\/path><path d=\"M11.4852 16.2739C11.3682 16.2209 11.2382 16.1853 11.1377 16.1103C11.0166 16.02 10.9107 15.9039 10.8159 15.785C10.6228 15.5429 10.652 15.2132 10.873 14.9945C11.0913 14.7783 11.4067 14.7541 11.65 14.9485C11.7689 15.0434 11.8807 15.152 11.9767 15.2698C12.1336 15.4626 12.1594 15.6843 12.0471 15.9079C11.9361 16.1287 11.7532 16.2473 11.4852 16.2739Z\" fill=\"white\"><\/path><path d=\"M12.2148 18.8714C11.757 18.8736 11.4479 18.371 11.6924 17.9885C11.805 17.8125 11.9741 17.6596 12.147 17.5382C12.3629 17.3866 12.6089 17.428 12.8203 17.5983C12.9993 17.7426 13.074 17.9959 13.0056 18.2273C12.9178 18.5246 12.4935 18.8701 12.2148 18.8714Z\" fill=\"white\"><\/path><path d=\"M11.7062 21.2496C11.6956 21.2496 11.6851 21.2502 11.6746 21.2495C11.3608 21.2313 10.9277 20.8013 10.9062 20.4875C10.8892 20.238 10.9846 20.0471 11.2007 19.9189C11.4187 19.7895 11.6391 19.7958 11.8378 19.9452C11.9752 20.0486 12.1051 20.171 12.2092 20.3071C12.3554 20.4984 12.36 20.7191 12.2474 20.9329C12.1342 21.1478 11.9484 21.25 11.7062 21.2496Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDietista <br> Ayuda\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b584b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d2b584b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M9.56687 25.2184C9.92102 24.8658 10.2626 24.522 10.6106 24.1848C10.6442 24.1522 10.7192 24.1458 10.7719 24.152C11.516 24.2403 12.2596 24.3331 13.0033 24.4243C13.3096 24.4618 13.6166 24.4936 13.9219 24.5375C14.0114 24.5504 14.064 24.5284 14.1215 24.4608C15.2018 23.192 16.2847 21.9253 17.3669 20.6581C17.9207 20.0096 18.4746 19.361 19.0283 18.7124C19.0814 18.6502 19.1336 18.5871 19.1984 18.5099C15.6447 17.1563 12.1122 15.8107 8.56641 14.4601C8.60712 14.4148 8.63469 14.3813 8.66523 14.3508C9.08793 13.9276 9.51207 13.506 9.93273 13.0809C9.99338 13.0196 10.048 12.9982 10.1376 13.0108C11.3062 13.1756 12.4753 13.3368 13.6452 13.4915C13.7211 13.5015 13.8169 13.4687 13.8833 13.4251C14.3741 13.1029 14.8491 12.7553 15.3517 12.4533C15.5852 12.3131 15.8627 12.2274 16.1316 12.1693C16.5355 12.0819 16.8102 12.3453 16.7297 12.7473C16.6739 13.0258 16.5493 13.2913 16.4473 13.5597C16.4111 13.6546 16.3506 13.7403 16.289 13.8525C16.482 13.8814 16.6673 13.8904 16.8416 13.9389C17.2329 14.0479 17.5373 13.936 17.8608 13.6927C18.2446 13.4039 18.6809 13.1786 19.1133 12.9639C19.2967 12.8729 19.5285 12.8466 19.7377 12.8488C19.9851 12.8514 20.1309 13.0387 20.1388 13.2886C20.1487 13.6035 20.0178 13.8791 19.888 14.1542C19.8616 14.2103 19.8331 14.2653 19.7975 14.3371C20.1909 14.3922 20.5624 14.445 20.9342 14.4963C21.4872 14.5728 22.0406 14.6459 22.5931 14.726C22.7089 14.7428 22.7905 14.7209 22.8777 14.6335C24.4347 13.0699 26.0249 11.5419 27.7665 10.1811C28.3885 9.69506 29.0244 9.22477 29.7402 8.8841C30.0242 8.7488 30.3301 8.64022 30.6378 8.57762C31.1639 8.47065 31.502 8.82608 31.4211 9.35872C31.3483 9.83876 31.1288 10.26 30.8868 10.6697C30.2836 11.6911 29.5346 12.6044 28.7641 13.5005C27.6801 14.7613 26.5266 15.9572 25.348 17.1292C25.2855 17.1915 25.2461 17.2483 25.2596 17.3446C25.3909 18.2757 25.5181 19.2072 25.6467 20.1387C25.648 20.148 25.6539 20.1566 25.6657 20.1848C25.7124 20.1633 25.7573 20.1389 25.8048 20.1213C26.0379 20.0345 26.2659 19.9237 26.5065 19.8693C26.9475 19.7697 27.2253 20.0341 27.1408 20.4784C27.094 20.7244 27.0126 20.9767 26.8882 21.1923C26.6344 21.6326 26.3397 22.0492 26.0652 22.4776C26.0305 22.5317 25.9908 22.6019 25.997 22.6597C26.0327 22.9858 26.0814 23.3105 26.1267 23.6354C26.1293 23.6539 26.1403 23.6712 26.146 23.6858C26.3695 23.5789 26.5856 23.4634 26.8113 23.3716C26.9546 23.3133 27.1102 23.2752 27.2639 23.2544C27.6446 23.203 27.9067 23.4604 27.826 23.8368C27.7663 24.1152 27.6801 24.4031 27.5357 24.6451C27.2352 25.1485 26.886 25.6227 26.5631 26.113C26.5218 26.1757 26.4904 26.2662 26.4999 26.3378C26.6447 27.435 26.7896 28.5322 26.9536 29.6267C26.9901 29.8706 26.9559 30.0383 26.7661 30.2139C26.3495 30.5992 25.9611 31.015 25.5384 31.4413C24.1813 27.8792 22.8349 24.345 21.4816 20.7928C21.2054 21.0276 20.9445 21.2486 20.6844 21.4707C18.9739 22.9318 17.2638 24.3936 15.5516 25.8527C15.4735 25.9192 15.4412 25.9774 15.4553 26.0868C15.5875 27.1166 15.7107 28.1476 15.8396 29.1778C15.8534 29.2878 15.8344 29.3684 15.7495 29.4507C15.4228 29.7677 15.1054 30.0941 14.7711 30.4303C14.6134 30.1211 14.4648 29.8301 14.3166 29.5389C13.9034 28.7273 13.4925 27.9147 13.0743 27.1057C13.0351 27.0299 12.9617 26.9564 12.8859 26.9174C11.8324 26.3753 10.7757 25.8395 9.71981 25.302C9.67307 25.2781 9.62769 25.2518 9.56687 25.2184Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVolver <br> Inicio\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f06f02 e-grid e-con-full elementor-hidden-desktop elementor-hidden-tablet e-con e-child\" data-id=\"4f06f02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-509c4b9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"509c4b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M9.56687 25.2184C9.92102 24.8658 10.2626 24.522 10.6106 24.1848C10.6442 24.1522 10.7192 24.1458 10.7719 24.152C11.516 24.2403 12.2596 24.3331 13.0033 24.4243C13.3096 24.4618 13.6166 24.4936 13.9219 24.5375C14.0114 24.5504 14.064 24.5284 14.1215 24.4608C15.2018 23.192 16.2847 21.9253 17.3669 20.6581C17.9207 20.0096 18.4746 19.361 19.0283 18.7124C19.0814 18.6502 19.1336 18.5871 19.1984 18.5099C15.6447 17.1563 12.1122 15.8107 8.56641 14.4601C8.60712 14.4148 8.63469 14.3813 8.66523 14.3508C9.08793 13.9276 9.51207 13.506 9.93273 13.0809C9.99338 13.0196 10.048 12.9982 10.1376 13.0108C11.3062 13.1756 12.4753 13.3368 13.6452 13.4915C13.7211 13.5015 13.8169 13.4687 13.8833 13.4251C14.3741 13.1029 14.8491 12.7553 15.3517 12.4533C15.5852 12.3131 15.8627 12.2274 16.1316 12.1693C16.5355 12.0819 16.8102 12.3453 16.7297 12.7473C16.6739 13.0258 16.5493 13.2913 16.4473 13.5597C16.4111 13.6546 16.3506 13.7403 16.289 13.8525C16.482 13.8814 16.6673 13.8904 16.8416 13.9389C17.2329 14.0479 17.5373 13.936 17.8608 13.6927C18.2446 13.4039 18.6809 13.1786 19.1133 12.9639C19.2967 12.8729 19.5285 12.8466 19.7377 12.8488C19.9851 12.8514 20.1309 13.0387 20.1388 13.2886C20.1487 13.6035 20.0178 13.8791 19.888 14.1542C19.8616 14.2103 19.8331 14.2653 19.7975 14.3371C20.1909 14.3922 20.5624 14.445 20.9342 14.4963C21.4872 14.5728 22.0406 14.6459 22.5931 14.726C22.7089 14.7428 22.7905 14.7209 22.8777 14.6335C24.4347 13.0699 26.0249 11.5419 27.7665 10.1811C28.3885 9.69506 29.0244 9.22477 29.7402 8.8841C30.0242 8.7488 30.3301 8.64022 30.6378 8.57762C31.1639 8.47065 31.502 8.82608 31.4211 9.35872C31.3483 9.83876 31.1288 10.26 30.8868 10.6697C30.2836 11.6911 29.5346 12.6044 28.7641 13.5005C27.6801 14.7613 26.5266 15.9572 25.348 17.1292C25.2855 17.1915 25.2461 17.2483 25.2596 17.3446C25.3909 18.2757 25.5181 19.2072 25.6467 20.1387C25.648 20.148 25.6539 20.1566 25.6657 20.1848C25.7124 20.1633 25.7573 20.1389 25.8048 20.1213C26.0379 20.0345 26.2659 19.9237 26.5065 19.8693C26.9475 19.7697 27.2253 20.0341 27.1408 20.4784C27.094 20.7244 27.0126 20.9767 26.8882 21.1923C26.6344 21.6326 26.3397 22.0492 26.0652 22.4776C26.0305 22.5317 25.9908 22.6019 25.997 22.6597C26.0327 22.9858 26.0814 23.3105 26.1267 23.6354C26.1293 23.6539 26.1403 23.6712 26.146 23.6858C26.3695 23.5789 26.5856 23.4634 26.8113 23.3716C26.9546 23.3133 27.1102 23.2752 27.2639 23.2544C27.6446 23.203 27.9067 23.4604 27.826 23.8368C27.7663 24.1152 27.6801 24.4031 27.5357 24.6451C27.2352 25.1485 26.886 25.6227 26.5631 26.113C26.5218 26.1757 26.4904 26.2662 26.4999 26.3378C26.6447 27.435 26.7896 28.5322 26.9536 29.6267C26.9901 29.8706 26.9559 30.0383 26.7661 30.2139C26.3495 30.5992 25.9611 31.015 25.5384 31.4413C24.1813 27.8792 22.8349 24.345 21.4816 20.7928C21.2054 21.0276 20.9445 21.2486 20.6844 21.4707C18.9739 22.9318 17.2638 24.3936 15.5516 25.8527C15.4735 25.9192 15.4412 25.9774 15.4553 26.0868C15.5875 27.1166 15.7107 28.1476 15.8396 29.1778C15.8534 29.2878 15.8344 29.3684 15.7495 29.4507C15.4228 29.7677 15.1054 30.0941 14.7711 30.4303C14.6134 30.1211 14.4648 29.8301 14.3166 29.5389C13.9034 28.7273 13.4925 27.9147 13.0743 27.1057C13.0351 27.0299 12.9617 26.9564 12.8859 26.9174C11.8324 26.3753 10.7757 25.8395 9.71981 25.302C9.67307 25.2781 9.62769 25.2518 9.56687 25.2184Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAeropuerto <br> Transferencia\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d72fe4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3d72fe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M12.0673 29.2272C12.0673 29.1879 12.0648 29.1718 12.0677 29.1567C12.4866 26.8929 12.9137 24.6306 13.3215 22.3648C13.4957 21.3968 13.9616 20.6243 14.7821 20.0901C16.0023 19.2957 17.3436 19.1495 18.7432 19.4451C19.6114 19.6284 20.3602 20.0426 20.9751 20.6932C21.2244 20.9569 21.5909 20.9606 21.8344 20.7263C22.0821 20.488 22.0861 20.1144 21.8354 19.8525C21.6868 19.6972 21.5351 19.5427 21.3704 19.4052C20.5075 18.6847 19.501 18.2973 18.3958 18.153C17.0128 17.9724 15.695 18.1846 14.4677 18.8591C13.496 19.393 12.7656 20.1624 12.3901 21.2146C12.2188 21.6947 12.1278 22.2066 12.0328 22.7102C11.5982 25.0137 11.1762 27.3195 10.7472 29.6242C10.6542 30.1241 10.9126 30.4442 11.4236 30.4454C11.9751 30.4468 12.5266 30.4457 13.078 30.4457C14.3175 30.4457 15.557 30.446 16.7965 30.4455C17.0731 30.4454 17.287 30.3326 17.4024 30.0751C17.5865 29.6645 17.2758 29.2282 16.8006 29.2278C15.288 29.2263 13.7754 29.2272 12.2627 29.2272H12.0673Z\" fill=\"white\"><\/path><path d=\"M18.0784 7.16492C18.3097 7.20699 18.5438 7.23751 18.7719 7.29291C20.2886 7.66131 21.485 8.46372 22.2245 9.87156C22.4797 10.3574 22.563 10.8929 22.647 11.4275C22.819 12.5205 22.9927 13.6133 23.1713 14.7052C23.2524 15.2012 22.9981 15.5117 22.4937 15.5152C21.8899 15.5195 21.286 15.5202 20.6824 15.5331C20.5996 15.5349 20.4995 15.5782 20.4388 15.6355C19.5415 16.484 18.4769 16.9046 17.2456 16.8255C16.1833 16.7573 15.2769 16.3093 14.5344 15.5437C14.449 15.4557 14.3681 15.4257 14.2474 15.4321C13.6603 15.4639 13.0727 15.488 12.4851 15.5102C12.1246 15.5238 11.8395 15.239 11.8693 14.8691C11.8946 14.5563 11.9564 14.2462 12.0058 13.9356C12.171 12.8946 12.3347 11.8533 12.5052 10.8132C12.6142 10.1488 12.915 9.56884 13.3434 9.05935C14.2652 7.96317 15.4584 7.36867 16.8705 7.1924C16.906 7.18796 16.9404 7.17429 16.9754 7.16492H18.0784ZM15.806 12.1592C15.6528 12.1453 15.5167 12.1382 15.3822 12.1197C15.0034 12.0675 14.7877 11.7958 14.8315 11.4327C14.8709 11.1062 15.1703 10.8883 15.5254 10.9209C16.6818 11.0273 17.6093 10.6117 18.3044 9.6845C18.5539 9.35156 18.7313 8.98006 18.8454 8.57113C18.4617 8.44384 18.0796 8.39437 17.6901 8.38182C16.3743 8.33925 15.2485 8.76361 14.3519 9.74293C14.024 10.101 13.7858 10.5149 13.7039 10.9986C13.5612 11.8411 13.4331 12.6861 13.2994 13.5302C13.2614 13.7703 13.2256 14.0108 13.1931 14.2235C13.574 14.2235 13.9351 14.2249 14.2962 14.2216C14.3348 14.2212 14.3764 14.1993 14.4113 14.1783C15.1751 13.7186 15.6203 13.0386 15.806 12.1592ZM15.5591 14.846C16.7475 15.975 18.7291 15.872 19.8367 14.4893C19.0134 13.631 18.5247 12.5883 18.2197 11.4875C17.8496 11.6469 17.4932 11.7963 17.1417 11.9566C17.0948 11.978 17.0509 12.0519 17.0433 12.1066C16.9065 13.0896 16.5097 13.9425 15.7917 14.637C15.717 14.7093 15.637 14.7762 15.5591 14.846ZM21.8678 14.2975C21.8609 14.2354 21.857 14.1785 21.848 14.1224C21.7046 13.2217 21.5387 12.324 21.4227 11.4198C21.3023 10.4813 20.8558 9.75717 20.1079 9.20136C20.0632 9.16817 20.0155 9.13913 19.9587 9.10114C19.7829 9.58315 19.567 10.0233 19.2757 10.4245C19.2526 10.4563 19.2507 10.5138 19.2582 10.556C19.3807 11.2408 19.5848 11.8993 19.908 12.5176C20.2739 13.2178 20.7578 13.8126 21.4373 14.2357C21.5739 14.3209 21.7091 14.3237 21.8678 14.2975Z\" fill=\"white\"><\/path><path d=\"M24.6575 22.5575C26.2272 22.5574 27.7971 22.5574 29.3669 22.5575C29.8763 22.5575 30.1007 22.7777 30.1008 23.2814C30.1013 25.4284 30.1011 27.5755 30.1005 29.7226C30.1003 30.1966 29.8485 30.4454 29.3683 30.4454C27.116 30.446 24.8636 30.4477 22.6113 30.4416C22.4457 30.4412 22.3257 30.4922 22.2038 30.5942C21.564 31.13 20.9191 31.6596 20.2767 32.1923C20.1205 32.3219 19.9477 32.4016 19.7414 32.3644C19.4651 32.3146 19.2834 32.1095 19.2524 31.8225C19.2473 31.7757 19.2482 31.7281 19.2482 31.6809C19.2481 28.8671 19.2479 26.0533 19.2483 23.2396C19.2483 22.8791 19.3737 22.6691 19.6523 22.5883C19.7509 22.5598 19.8596 22.5587 19.9638 22.5587C21.5283 22.5569 23.0929 22.5575 24.6575 22.5575ZM20.4795 23.7786V30.4672C20.9022 30.114 21.3081 29.7825 21.7044 29.4401C21.882 29.2866 22.0746 29.224 22.3079 29.2245C24.4345 29.229 26.561 29.2272 28.6876 29.2272H28.88V23.7786H20.4795Z\" fill=\"white\"><\/path><path d=\"M12.0673 29.2272H12.2627C13.7754 29.2272 15.288 29.2263 16.8006 29.2278C17.2758 29.2282 17.5865 29.6645 17.4024 30.0751C17.287 30.3326 17.0731 30.4454 16.7965 30.4455C15.557 30.446 14.3175 30.4457 13.078 30.4457C12.5266 30.4457 11.9751 30.4468 11.4236 30.4454C10.9126 30.4442 10.6542 30.1241 10.7472 29.6242C11.1762 27.3195 11.5982 25.0137 12.0328 22.7102C12.1278 22.2066 12.2188 21.6947 12.3901 21.2146C12.7656 20.1624 13.496 19.393 14.4677 18.8591C15.695 18.1846 17.0128 17.9724 18.3958 18.153C19.501 18.2973 20.5075 18.6847 21.3704 19.4052C21.5351 19.5427 21.6868 19.6972 21.8354 19.8525C22.0861 20.1144 22.0821 20.488 21.8344 20.7263C21.5909 20.9606 21.2244 20.9569 20.9751 20.6932C20.3602 20.0426 19.6114 19.6284 18.7432 19.4451C17.3436 19.1495 16.0023 19.2957 14.7821 20.0901C13.9616 20.6243 13.4957 21.3968 13.3215 22.3648C12.9137 24.6306 12.4866 26.8929 12.0677 29.1567C12.0648 29.1718 12.0673 29.1879 12.0673 29.2272Z\" fill=\"white\"><\/path><path d=\"M24.5755 24.335C23.5066 24.3603 22.6048 25.2734 22.5909 26.3444C22.5862 26.7016 22.8275 26.9737 23.163 26.9897C23.5082 27.0061 23.7799 26.7557 23.8062 26.3966C23.8442 25.8776 24.1339 25.5907 24.6504 25.5373C24.7752 25.5245 24.9118 25.4845 25.0131 25.4141C25.2455 25.2525 25.3126 24.9908 25.2208 24.7308C25.1277 24.4667 24.9004 24.3274 24.5755 24.335ZM24.7532 28.4401C24.7562 28.4399 24.7929 28.4381 24.8296 28.4355C25.8652 28.3635 26.7232 27.4398 26.7139 26.4073C26.7108 26.0593 26.465 25.7938 26.1352 25.7825C25.7888 25.7706 25.5289 26.0121 25.5053 26.3679C25.4703 26.8934 25.1615 27.2015 24.6342 27.2369C24.2869 27.2602 24.0247 27.5434 24.0482 27.8697C24.0744 28.2328 24.3522 28.4699 24.7532 28.4401Z\" fill=\"white\"><\/path><path d=\"M24.5755 24.335C24.9004 24.3274 25.1277 24.4668 25.2209 24.7308C25.3126 24.9908 25.2455 25.2525 25.0131 25.4141C24.9118 25.4846 24.7752 25.5245 24.6504 25.5374C24.1339 25.5907 23.8442 25.8776 23.8062 26.3966C23.7799 26.7557 23.5082 27.0062 23.163 26.9897C22.8275 26.9737 22.5862 26.7016 22.5909 26.3444C22.6048 25.2734 23.5066 24.3603 24.5755 24.335Z\" fill=\"white\"><\/path><path d=\"M24.7534 28.4401C24.3523 28.4698 24.0746 28.2328 24.0483 27.8697C24.0248 27.5434 24.287 27.2602 24.6343 27.2368C25.1617 27.2014 25.4705 26.8933 25.5054 26.3678C25.5291 26.012 25.7889 25.7706 26.1354 25.7824C26.4651 25.7938 26.7109 26.0592 26.714 26.4072C26.7233 27.4397 25.8653 28.3634 24.8297 28.4355C24.793 28.438 24.7563 28.4399 24.7534 28.4401Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTraductor <br><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1eaee elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1c1eaee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M11.4162 14.438H11.3174C10.6263 14.438 9.93524 14.4381 9.24418 14.438C8.58747 14.4379 8.11146 13.9613 8.11142 13.3038C8.11138 12.1884 8.11118 11.073 8.11155 9.95765C8.11192 8.79444 9.00833 7.89642 10.1726 7.8954C11.6517 7.89412 13.1308 7.89507 14.6099 7.89507C18.3028 7.89507 21.9957 7.89157 25.6886 7.89749C26.6216 7.89901 27.2677 8.36902 27.6629 9.19808C27.8024 9.49077 27.858 9.80543 27.8579 10.1302C27.8572 11.7038 27.8575 13.2775 27.8575 14.8512V14.9407H27.9559C28.95 14.9407 29.9442 14.9408 30.9383 14.9406C31.4889 14.9406 31.8886 15.3396 31.8888 15.8902C31.8889 16.4043 31.8891 16.9184 31.8887 17.4324C31.8883 17.9667 31.5042 18.3603 30.9693 18.3758C30.9504 18.3764 30.9317 18.3793 30.9055 18.3818V18.5005C30.9055 21.9534 30.9055 25.4062 30.9054 28.859C30.9054 30.3903 29.8443 31.7066 28.3484 32.0314C26.7142 32.3862 25.0912 31.439 24.5869 29.8326C24.5625 29.7549 24.5292 29.7355 24.4519 29.7355C20.6596 29.7374 16.8673 29.7373 13.075 29.7371C12.2745 29.7371 11.6026 29.1933 11.4398 28.4098C11.4168 28.2991 11.4054 28.1838 11.4053 28.0707C11.4035 26.7419 11.4048 25.4131 11.4057 24.0844C11.4061 23.4249 11.4077 22.7654 11.4084 22.1059C11.4095 20.9008 11.4101 19.6957 11.4114 18.4906C11.4127 17.1692 11.4146 15.8478 11.4162 14.5263V14.438ZM24.4312 21.8613H24.3207C20.9239 21.8613 17.5271 21.8613 14.1303 21.8612C14.0963 21.8612 14.0623 21.8621 14.0285 21.8601C13.9193 21.8536 13.8252 21.8123 13.7552 21.7274C13.6553 21.6062 13.6334 21.4687 13.6982 21.3259C13.7684 21.1711 13.8957 21.1021 14.0655 21.1021C17.4868 21.1028 20.908 21.1026 24.3292 21.1026H24.4298V19.1985H24.3313C20.927 19.1985 17.5228 19.1985 14.1185 19.1984C14.0822 19.1984 14.0456 19.1994 14.0095 19.1958C13.8171 19.1767 13.6749 19.0278 13.6634 18.8352C13.6528 18.6575 13.7769 18.4906 13.9546 18.4505C14.0035 18.4394 14.0556 18.4402 14.1063 18.4401C17.5178 18.4397 20.9293 18.4396 24.3409 18.4396C24.3626 18.4396 24.3851 18.4421 24.406 18.4377C24.4166 18.4355 24.431 18.4214 24.4321 18.4114C24.4333 18.4013 24.4224 18.3837 24.4127 18.3799C24.3978 18.3741 24.3794 18.3769 24.3624 18.3765C23.8426 18.3639 23.45 17.9614 23.4492 17.4395C23.4487 17.1656 23.4491 16.8916 23.4491 16.6176V16.5317H23.3251C20.2676 16.5317 17.2101 16.5317 14.1525 16.5317C14.1113 16.5317 14.07 16.5333 14.0289 16.5309C13.832 16.519 13.6881 16.3825 13.666 16.1881C13.6457 16.0103 13.7605 15.8365 13.936 15.7894C13.9912 15.7745 14.051 15.7718 14.1087 15.7718C17.1759 15.771 20.2431 15.7711 23.3103 15.7711C23.3394 15.7711 23.3687 15.769 23.3976 15.7716C23.442 15.7756 23.4586 15.7594 23.4679 15.7133C23.5654 15.2294 23.9214 14.94 24.4154 14.9399C25.2786 14.9397 26.1418 14.9399 27.005 14.9397C27.0351 14.9397 27.0653 14.9367 27.0995 14.9349V14.8392C27.0995 13.268 27.0993 11.6969 27.0998 10.1257C27.0999 9.94668 27.0694 9.7735 27.0106 9.60505C26.8136 9.04065 26.2966 8.65344 25.7359 8.6534C21.0976 8.65299 16.4592 8.65312 11.8207 8.65328C11.7953 8.65328 11.77 8.65562 11.7459 8.65677C11.7448 8.66585 11.7445 8.67021 11.7445 8.67021C11.7741 8.71435 11.805 8.7577 11.8337 8.8025C12.0884 9.20104 12.1828 9.63546 12.1799 10.109C12.1686 11.9783 12.1735 13.8478 12.1721 15.7171C12.1708 17.5696 12.1693 19.422 12.1678 21.2744C12.167 22.2418 12.1659 23.2092 12.1651 24.1767C12.1639 25.4714 12.1624 26.7661 12.162 28.0609C12.1619 28.5846 12.5509 28.9782 13.0681 28.9783C16.8288 28.9786 20.5894 28.9784 24.3501 28.9784H24.4303V27.1852H24.3315H14.1333C14.0969 27.1852 14.0604 27.1873 14.0242 27.1846C13.877 27.1735 13.7656 27.104 13.702 26.97C13.6373 26.8338 13.6508 26.7003 13.7404 26.5787C13.8291 26.4584 13.9545 26.4256 14.099 26.4257C17.5057 26.427 20.9123 26.4267 24.319 26.4267H24.4304V24.5224H24.3338C20.9199 24.5224 17.5059 24.5224 14.092 24.5224C14.0702 24.5224 14.0483 24.5229 14.0265 24.5221C13.8419 24.5151 13.6921 24.3772 13.6676 24.192C13.6433 24.0084 13.7535 23.8321 13.9313 23.7829C13.9908 23.7664 14.0557 23.7645 14.1182 23.7645C17.5176 23.7637 20.917 23.7638 24.3164 23.7638H24.4312V21.8613ZM25.2071 25.9606C25.2071 26.9254 25.2079 27.8903 25.2066 28.8551C25.2063 29.1216 25.2432 29.3818 25.3284 29.6339C25.8222 31.0958 27.4639 31.7653 28.8249 31.0379C29.6719 30.5851 30.1231 29.8493 30.1309 28.8883C30.1471 26.8812 30.1358 24.8738 30.1357 22.8666C30.1357 22.7661 30.1356 22.7659 30.0382 22.7659C28.4625 22.7659 26.8868 22.7659 25.3111 22.7659C25.2075 22.7659 25.2072 22.7661 25.2072 22.8697C25.2071 23.9001 25.2072 24.9303 25.2071 25.9606ZM30.1423 18.3832H25.1989V21.9901H30.1423V18.3832ZM11.4148 13.6747C11.4148 13.6401 11.4148 13.6116 11.4148 13.583C11.4153 12.3732 11.4151 11.1634 11.417 9.95354C11.4175 9.6713 11.3364 9.41634 11.1636 9.19574C10.8805 8.83426 10.5148 8.62357 10.0452 8.66257C9.35707 8.71973 8.87066 9.26338 8.87037 9.95506C8.86988 11.0704 8.87017 12.1856 8.87029 13.3009C8.87029 13.543 9.00583 13.6781 9.24965 13.6782C9.94305 13.6786 10.6365 13.6786 11.3299 13.6785C11.3559 13.6785 11.3819 13.6763 11.4148 13.6747ZM27.2552 15.701V15.7901C27.2552 15.9089 27.2566 16.0278 27.2548 16.1466C27.2517 16.3603 27.0967 16.5224 26.888 16.5325C26.6906 16.5421 26.5184 16.3947 26.4985 16.1878C26.4876 16.0749 26.4938 15.9602 26.4926 15.8464C26.4922 15.801 26.4925 15.7556 26.4925 15.7056H25.6638C25.6638 15.7365 25.6639 15.7625 25.6638 15.7885C25.6636 15.9121 25.6668 16.0359 25.6623 16.1594C25.6544 16.3757 25.4848 16.5375 25.2767 16.5325C25.0658 16.5274 24.9053 16.3617 24.9035 16.1461C24.9026 16.0297 24.9035 15.9133 24.9034 15.797C24.9033 15.7008 24.9033 15.7007 24.8107 15.7007C24.6797 15.7005 24.5488 15.7004 24.4179 15.7007C24.2671 15.701 24.2121 15.7555 24.212 15.9069C24.2115 16.4016 24.2117 16.8962 24.2116 17.3908C24.2116 17.5677 24.2594 17.6159 24.4349 17.6159C26.1758 17.6159 27.9167 17.6159 29.6576 17.6159C30.0868 17.6159 30.516 17.6162 30.9452 17.6156C31.0647 17.6155 31.1292 17.5549 31.1294 17.4397C31.1303 16.9184 31.1303 16.3971 31.1294 15.8758C31.1292 15.7666 31.0666 15.703 30.958 15.7013C30.8053 15.699 30.6525 15.7025 30.4998 15.6997C30.4473 15.6987 30.4339 15.7188 30.4349 15.7679C30.4375 15.8988 30.4373 16.0298 30.4353 16.1607C30.4324 16.3578 30.2859 16.5117 30.0853 16.5313C29.9041 16.5491 29.7286 16.4214 29.6882 16.2383C29.6778 16.1915 29.6765 16.1422 29.6759 16.094C29.6742 15.9661 29.6753 15.8383 29.6753 15.7078H28.8464C28.8464 15.8552 28.8475 15.9955 28.8461 16.1358C28.8438 16.3656 28.6776 16.5359 28.4609 16.5326C28.2461 16.5293 28.0873 16.3605 28.0861 16.1335C28.0855 16.0098 28.0856 15.8862 28.0862 15.7625C28.0863 15.7285 28.0857 15.7003 28.0384 15.7005C27.7817 15.7016 27.525 15.701 27.2552 15.701Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><path d=\"M19.6281 10.4482C21.4801 10.4482 23.3321 10.4482 25.1842 10.4483C25.3866 10.4483 25.5291 10.5428 25.5834 10.7119C25.6608 10.9525 25.4881 11.195 25.2301 11.2075C25.2107 11.2084 25.1913 11.2078 25.1719 11.2078C21.4799 11.2078 17.7879 11.2079 14.0959 11.2072C14.043 11.2072 13.9884 11.204 13.9377 11.1906C13.769 11.1461 13.6524 10.9784 13.665 10.8069C13.6787 10.6204 13.8117 10.4756 13.9921 10.4528C14.028 10.4482 14.0646 10.4484 14.1009 10.4484C15.9433 10.4482 17.7857 10.4482 19.6281 10.4482Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><path d=\"M19.6375 13.1115C21.4871 13.1115 23.3368 13.1114 25.1864 13.1115C25.3882 13.1115 25.5315 13.2075 25.5842 13.3768C25.6589 13.6163 25.4908 13.8542 25.2355 13.87C25.2113 13.8716 25.1869 13.8707 25.1627 13.8707C21.4828 13.8708 17.803 13.8708 14.123 13.8705C14.0747 13.8705 14.0257 13.8705 13.9783 13.8624C13.7918 13.831 13.6586 13.6679 13.6642 13.4823C13.6703 13.2872 13.8153 13.1316 14.0087 13.1136C14.0327 13.1113 14.0571 13.1115 14.0813 13.1115C15.9333 13.1114 17.7855 13.1115 19.6375 13.1115Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.2\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPrueba preoperatoria <br><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3b9b7e elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d3b9b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M10.6055 17.9271C10.6693 17.7327 10.7515 17.5518 10.9152 17.4153C11.0867 17.2725 11.2904 17.2328 11.5011 17.2024C13.2387 16.9515 14.9759 16.6984 16.7138 16.4499C16.7997 16.4376 16.8199 16.3829 16.8486 16.3247C17.5216 14.9617 18.1944 13.5986 18.8671 12.2354C18.9795 12.0077 19.0936 11.7807 19.2028 11.5514C19.3641 11.2127 19.6271 11.0201 20.0041 11.0212C20.377 11.0224 20.633 11.2191 20.7957 11.5495C21.5313 13.0429 22.2684 14.5355 23.0049 16.0284C23.0412 16.102 23.0886 16.1722 23.112 16.2496C23.1601 16.4084 23.2695 16.4501 23.4227 16.4717C24.7081 16.6527 25.9924 16.8417 27.277 17.0287C27.7567 17.0986 28.2389 17.155 28.7151 17.2438C29.3414 17.3606 29.6081 18.1228 29.1998 18.6131C29.0601 18.7807 28.8939 18.9266 28.7371 19.0796C27.5824 20.2053 26.4276 21.3309 25.2705 22.4541C25.2066 22.5161 25.1918 22.5697 25.207 22.6579C25.5142 24.4298 25.8186 26.2022 26.1193 27.9752C26.175 28.3037 26.0624 28.5807 25.8018 28.7855C25.5531 28.9808 25.2641 29.0397 24.9744 28.9077C24.6085 28.7411 24.2564 28.5441 23.9001 28.3571C22.63 27.6905 21.3601 27.0234 20.0921 26.3529C20.0184 26.3139 19.967 26.3224 19.8997 26.3578C18.3264 27.1869 16.7522 28.0142 15.1782 28.8418C14.7216 29.0819 14.2529 28.9724 13.9963 28.564C13.8858 28.3882 13.8429 28.1938 13.8774 27.9905C14.0966 26.6993 14.3197 25.4087 14.5415 24.118C14.6282 23.6133 14.7169 23.1088 14.798 22.6032C14.8046 22.5618 14.7706 22.501 14.737 22.468C14.0749 21.8184 13.41 21.1715 12.7455 20.5242C12.1596 19.9533 11.5761 19.3799 10.986 18.8133C10.8068 18.6413 10.6647 18.4531 10.6055 18.209V17.9271Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9xito <br> Cirug\u00eda\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9426a6 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f9426a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M23.5591 6.05908C23.9071 6.15114 24.234 6.28429 24.4641 6.57695C24.836 7.05013 24.9342 7.57463 24.6791 8.1271C24.4159 8.69691 23.9458 8.98911 23.3187 8.99124C21.3932 8.99777 19.4677 8.99456 17.5422 8.99302C17.1701 8.99271 16.7928 9.0206 16.4273 8.96932C15.7261 8.87098 15.2223 8.29844 15.1834 7.62099C15.1427 6.91258 15.5583 6.3295 16.2557 6.11637C16.3164 6.0978 16.3768 6.07821 16.4373 6.05908H23.5591ZM19.6865 7.51315C19.685 7.02632 19.4037 6.71736 18.9607 6.71593C18.5181 6.7145 18.2074 7.03432 18.2054 7.49343C18.2031 7.99321 18.4821 8.3056 18.9324 8.30762C19.3824 8.30964 19.6879 7.98784 19.6865 7.51315ZM17.0389 6.74934C16.9788 6.74473 16.9438 6.74473 16.9097 6.73897C16.7348 6.70937 16.6778 6.77556 16.6867 6.95608C16.7026 7.27489 16.6911 7.59505 16.6911 7.91466V8.27302H17.0486V7.6447H17.6262V8.27473H17.9609V6.75426H17.616V7.31528H17.0389V6.74934ZM22.0878 7.99011H21.4755V7.62183H22.0202V7.34953H21.4729V7.02699H22.0517V6.75234H21.1259V8.27065H22.0878V7.99011ZM20.1563 7.02922V8.26981H20.5073V7.02262H20.9181V6.75238H19.7536V7.02922H20.1563ZM22.6781 7.98284V6.75046H22.3467V8.27358H23.291V7.98284H22.6781Z\" fill=\"white\"><\/path><path d=\"M28.9198 12.583H28.3784V31.9947H29.4163V33.9406H10.584V32.0011H11.6188V12.5893H11.0775V9.45215H28.9198V12.583ZM17.1116 31.9886H22.8929V26.2473H23.2799H23.6759C23.5986 24.7906 22.9862 23.6697 21.696 23.0078C20.2754 22.2791 18.8935 22.4415 17.6504 23.4315C16.7644 24.1372 16.334 25.0939 16.3217 26.2527H17.1116V31.9886ZM18.5234 21.5205H21.4749V18.5787H18.5234V21.5205ZM21.4762 13.6245H18.5278V16.5587H21.4762V13.6245ZM16.6935 18.5848H13.746V21.5254H16.6935V18.5848ZM26.2569 18.5843H23.3035V21.52H26.2569V18.5843ZM13.7426 16.5547C13.7761 16.5612 13.7979 16.5691 13.8198 16.5692C14.739 16.5703 15.6582 16.5687 16.5773 16.5732C16.7136 16.5738 16.7061 16.4954 16.706 16.4038C16.7051 15.5322 16.7021 14.6607 16.7087 13.7892C16.7098 13.6418 16.6634 13.6042 16.521 13.6052C15.6542 13.611 14.7874 13.6079 13.9206 13.6086C13.8643 13.6086 13.808 13.6152 13.7426 13.6192V16.5547ZM26.2545 13.6249C26.2215 13.6184 26.1996 13.6104 26.1778 13.6103C25.2586 13.6092 24.3394 13.6108 23.4202 13.6063C23.2843 13.6056 23.2911 13.6833 23.2912 13.7753C23.2922 14.6469 23.2951 15.5185 23.2886 16.39C23.2875 16.5369 23.3331 16.5752 23.4759 16.5743C24.3427 16.5684 25.2095 16.5715 26.0764 16.5709C26.1327 16.5708 26.189 16.5643 26.2545 16.5602V13.6249Z\" fill=\"white\"><\/path><path d=\"M18.5625 7.53296C18.5754 7.45503 18.5829 7.39178 18.5966 7.32995C18.6451 7.10949 18.7734 6.99191 18.9566 6.99672C19.1256 7.00109 19.2745 7.12757 19.2945 7.33211C19.3098 7.48848 19.2946 7.65521 19.2546 7.80732C19.2169 7.95035 19.0972 8.03159 18.9357 8.02488C18.7769 8.01832 18.6752 7.9337 18.6253 7.78941C18.5954 7.70287 18.5811 7.61088 18.5625 7.53296Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLujo <br> Hotel\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c5cd40 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2c5cd40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M26.4052 28.4863C25.8149 28.3145 25.2908 28.1184 24.7491 28.0157C24.1063 27.8937 23.4751 28.0282 22.894 28.3304C22.4471 28.5629 22.0259 28.5589 21.5761 28.3306C20.5137 27.7914 19.4421 27.8061 18.3827 28.3475C17.998 28.5441 17.6159 28.5793 17.2265 28.3852C16.1069 27.8271 14.9992 27.8417 13.8993 28.4399C13.8238 28.481 13.7417 28.5099 13.6136 28.5659C13.2597 27.9005 12.8972 27.2512 12.5648 26.5868C12.0455 25.5486 11.6359 24.4672 11.3598 23.3373C11.3187 23.1688 11.2879 23.0416 11.4985 22.9297C13.9092 21.6484 16.421 20.6318 19.077 19.982C19.6806 19.8343 20.2806 19.826 20.8836 19.9725C23.5599 20.623 26.0925 21.6415 28.5157 22.9431C28.6531 23.0168 28.701 23.0895 28.6647 23.2402C28.2072 25.1394 27.3736 26.8738 26.4052 28.4863Z\" fill=\"white\"><\/path><path d=\"M28.9061 22.2068C28.156 21.8391 27.4921 21.5015 26.8181 21.1855C24.9823 20.3248 23.0729 19.6712 21.1066 19.1807C20.3475 18.9913 19.5919 19.0024 18.8341 19.1929C16.329 19.8226 13.9315 20.7324 11.6472 21.9397C11.4853 22.0253 11.3177 22.1002 11.0702 22.2201C11.0238 21.2592 10.9768 20.3616 10.9398 19.4637C10.9305 19.2378 11.0918 19.126 11.2733 19.0221C13.4724 17.7641 15.8029 16.8653 18.2979 16.3935C19.0888 16.244 19.8645 16.0204 20.6829 16.175C23.3591 16.6805 25.9496 17.4295 28.3247 18.8099C29.0963 19.2583 29.0942 19.0388 29.0551 20.1001C29.0299 20.7833 28.9602 21.4647 28.9061 22.2068Z\" fill=\"white\"><\/path><path d=\"M21.6998 8.99516H20.3816V11.8796C20.5413 11.8796 20.6538 11.8815 20.7661 11.8794C22.8137 11.8413 24.8475 12.0158 26.8772 12.2654C27.1132 12.2944 27.215 12.3901 27.1962 12.6213C27.1954 12.631 27.1962 12.6409 27.1964 12.6507C27.2087 13.2634 27.2087 13.2634 26.5846 13.3142V17.2469C26.238 17.1142 25.9437 16.9989 25.6476 16.8886C23.9518 16.2574 22.2205 15.7539 20.4355 15.445C19.8383 15.3417 19.2632 15.4869 18.6882 15.6111C16.9963 15.9765 15.3468 16.4822 13.7395 17.1252C13.6509 17.1606 13.5596 17.1887 13.427 17.2351V13.355C13.3735 13.3221 13.3584 13.3068 13.3408 13.3028C13.1755 13.2654 12.8906 13.2663 12.8665 13.1873C12.7955 12.9537 12.8056 12.6864 12.8341 12.4381C12.8418 12.3711 13.0235 12.2885 13.1333 12.2742C15.1611 12.0096 17.1956 11.8405 19.2432 11.8803C19.3479 11.8823 19.4526 11.8805 19.5813 11.8805C19.612 10.9042 19.6416 9.96498 19.6718 9.00182H18.2999C18.2999 9.45475 18.3013 9.90338 18.2995 10.3521C18.298 10.7111 18.2288 10.7844 17.9038 10.7828C17.5879 10.7811 17.5227 10.706 17.5209 10.3388C17.5188 9.91641 17.5178 9.49401 17.5151 9.07162C17.515 9.05352 17.5033 9.03548 17.519 9.08058C17.3429 8.97853 17.2111 8.90213 17.0791 8.82573C17.2015 8.7564 17.3238 8.68707 17.5212 8.57506C17.5212 8.23809 17.5204 7.81092 17.5215 7.38376C17.5225 7.01029 17.6018 6.94049 17.9727 6.95128C18.209 6.95818 18.3052 7.07025 18.3014 7.3024C18.2946 7.72267 18.2995 8.14306 18.2995 8.60513C18.7736 8.56917 19.2169 8.53562 19.741 8.49589C19.741 7.99037 19.7352 7.5019 19.746 7.01377C19.7481 6.91774 19.787 6.7894 19.8557 6.73457C20.0156 6.607 20.2427 6.7239 20.2475 6.93713C20.259 7.44571 20.2512 7.95471 20.2512 8.49336C20.7689 8.5345 21.2134 8.56988 21.6997 8.60855C21.6997 8.17248 21.6982 7.76294 21.7002 7.3534C21.7019 7.01666 21.7661 6.95323 22.0918 6.95393C22.4174 6.9547 22.4774 7.01578 22.4788 7.35976C22.4805 7.7897 22.4792 8.21964 22.4792 8.58426C22.6593 8.68666 22.7874 8.75953 22.9155 8.83245C22.7905 8.90408 22.6656 8.97576 22.4793 9.08258C22.4793 9.45923 22.4805 9.91817 22.4789 10.3771C22.4777 10.7037 22.3989 10.7837 22.0859 10.7858C21.7814 10.7878 21.7018 10.705 21.7003 10.3725C21.6982 9.92242 21.6998 9.47232 21.6998 8.99516ZM18.4506 14.5683V14.5702H18.9808C19.7592 14.5702 19.7806 14.5475 19.7519 13.7528C19.7409 13.4501 19.6423 13.3454 19.3415 13.3423C18.8703 13.3373 18.3989 13.3497 17.9279 13.339C17.0774 13.3197 17.12 13.3728 17.127 14.186C17.1291 14.434 17.251 14.5695 17.5082 14.5686C17.8223 14.5675 18.1365 14.5683 18.4506 14.5683ZM21.5635 13.3409C21.377 13.3409 21.1905 13.3408 21.0039 13.3409C20.2442 13.3411 20.2192 13.3676 20.2454 14.1428C20.2562 14.4619 20.3549 14.566 20.6733 14.5692C21.1445 14.5739 21.6161 14.5599 22.0869 14.5725C22.9096 14.5944 22.8856 14.5291 22.8734 13.707C22.8733 13.6972 22.8724 13.6874 22.8713 13.6776C22.8475 13.4592 22.7343 13.3398 22.506 13.3412C22.1919 13.3431 21.8777 13.3417 21.5635 13.3409ZM15.3183 13.3424V13.3409C15.1415 13.3409 14.9647 13.3408 14.7879 13.341C14.0012 13.3419 13.9804 13.3635 14.0069 14.1487C14.0177 14.4675 14.1144 14.5663 14.4382 14.569C14.8998 14.573 15.3617 14.5588 15.8229 14.5726C16.7128 14.5991 16.6356 14.4992 16.6311 13.7018C16.6298 13.4633 16.5006 13.3425 16.2611 13.3424C15.9468 13.3423 15.6326 13.3424 15.3183 13.3424ZM24.6718 14.5702C24.8485 14.5702 25.0254 14.5649 25.202 14.571C26.0962 14.6023 25.9868 14.4771 25.9889 13.7135C25.9895 13.4703 25.864 13.3364 25.6011 13.3402C25.12 13.3473 24.6388 13.3409 24.1577 13.3412C23.355 13.3417 23.3364 13.3615 23.3673 14.1673C23.3786 14.4616 23.4815 14.5639 23.7881 14.569C24.0825 14.5738 24.3772 14.57 24.6718 14.5702Z\" fill=\"white\"><\/path><path d=\"M33.0085 29.1426C32.4361 29.3631 31.8742 29.6194 31.2878 29.7924C30.8352 29.9258 30.3695 29.817 29.9421 29.6113C29.2346 29.2708 28.5484 29.2894 27.8599 29.6773C27.0682 30.1233 26.2478 30.1436 25.4331 29.7453C24.7633 29.4177 24.1227 29.428 23.462 29.7782C22.6445 30.2112 21.8019 30.224 20.9746 29.8008C20.3204 29.4662 19.6895 29.4639 19.0319 29.7987C18.1962 30.224 17.345 30.2102 16.5168 29.7684C15.8783 29.4279 15.2499 29.4111 14.6011 29.7314C13.7655 30.144 12.9312 30.1188 12.1188 29.6671C11.461 29.3014 10.8017 29.2695 10.1175 29.5848C9.3101 29.957 8.52379 29.9146 7.75364 29.4585C7.51088 29.3148 7.24046 29.2179 6.99121 29.0614C7.28485 29.1478 7.58799 29.2108 7.87019 29.3252C8.58216 29.614 9.26288 29.5899 9.93258 29.2031C10.7215 28.7476 11.5322 28.717 12.3557 29.1093C13.014 29.423 13.6581 29.4106 14.3022 29.0583C15.1271 28.6071 15.9728 28.5837 16.814 29.0055C17.4609 29.3299 18.0865 29.329 18.729 28.9938C19.582 28.5487 20.4454 28.5569 21.2973 29.0041C21.9188 29.3303 22.5314 29.3306 23.1576 29.0154C23.9972 28.5927 24.8442 28.598 25.6709 29.0447C26.3359 29.4041 26.9887 29.4201 27.6706 29.0956C28.4707 28.715 29.2728 28.7438 30.0404 29.188C30.7414 29.5936 31.4453 29.6191 32.1835 29.3045C32.4326 29.1982 32.7042 29.1446 32.9655 29.0669C32.9799 29.0921 32.9942 29.1174 33.0085 29.1426Z\" fill=\"white\"><\/path><path d=\"M32.2619 30.9265C32.0474 31.0195 31.8267 31.1008 31.6194 31.2078C30.9038 31.5771 30.1718 31.6158 29.4289 31.3164C28.7496 31.0426 28.0967 31.0698 27.439 31.3945C26.7132 31.7529 25.9581 31.7759 25.2154 31.458C24.5392 31.1685 23.8957 31.1772 23.2282 31.4913C22.5198 31.8245 21.7707 31.8503 21.0561 31.5325C20.3435 31.2157 19.6783 31.2019 18.9603 31.5263C18.2071 31.8667 17.426 31.8096 16.6778 31.4552C16.082 31.1729 15.4891 31.1631 14.8853 31.4223C14.0809 31.7675 13.2816 31.7574 12.4945 31.3667C11.8768 31.0601 11.2527 31.0455 10.6158 31.3021C9.84189 31.6139 9.08536 31.5836 8.34333 31.1887C8.14631 31.0839 7.9319 31.0118 7.73535 30.8789C7.9658 30.9413 8.20379 30.9842 8.42533 31.0697C9.11548 31.3361 9.78129 31.3141 10.4449 30.9761C11.1979 30.5926 11.9701 30.5761 12.7492 30.9069C13.3731 31.1718 13.9848 31.1517 14.598 30.8547C15.3756 30.4782 16.1735 30.461 16.9623 30.8117C17.5975 31.0942 18.2057 31.0792 18.8358 30.7891C19.5975 30.4383 20.3839 30.4341 21.1468 30.7834C21.7974 31.0813 22.4204 31.088 23.0764 30.7965C23.8224 30.465 24.5922 30.4705 25.3306 30.8255C26.0043 31.1494 26.6569 31.1642 27.346 30.8732C28.0818 30.5626 28.8263 30.6031 29.5387 30.968C30.2002 31.3068 30.8662 31.3409 31.5583 31.0752C31.7826 30.9891 32.0215 30.9407 32.2537 30.8751C32.2565 30.8923 32.2592 30.9093 32.2619 30.9265Z\" fill=\"white\"><\/path><path d=\"M30.9762 32.5791C30.763 32.675 30.547 32.7652 30.3371 32.8677C29.7492 33.1546 29.1389 33.1963 28.539 32.9554C27.8755 32.6892 27.2565 32.7027 26.6111 33.0212C25.9932 33.3261 25.3307 33.3355 24.6973 33.0626C24.0779 32.7957 23.4941 32.8008 22.8823 33.0868C22.2282 33.3925 21.5438 33.3945 20.8841 33.0995C20.2894 32.8336 19.7203 32.8272 19.1244 33.0947C18.4439 33.4002 17.7445 33.3867 17.0706 33.0707C16.4995 32.8029 15.9462 32.7885 15.3666 33.0371C14.6812 33.3312 13.9862 33.3216 13.3151 32.9902C12.7212 32.6968 12.135 32.685 11.5248 32.9323C10.8698 33.1977 10.2224 33.1575 9.59145 32.8332C9.40976 32.7399 9.21792 32.6662 9.03906 32.5428C9.22853 32.5934 9.42502 32.6262 9.6063 32.6978C10.2484 32.9511 10.8648 32.9154 11.4809 32.6027C12.1106 32.2832 12.7706 32.2635 13.4186 32.5333C14.0182 32.783 14.5905 32.7885 15.1793 32.5049C15.8725 32.1709 16.5841 32.1659 17.287 32.4794C17.8435 32.7275 18.3834 32.7172 18.9354 32.4623C19.6224 32.1451 20.329 32.1335 21.0168 32.4452C21.6111 32.7146 22.1739 32.7168 22.7747 32.4535C23.4429 32.1605 24.136 32.172 24.7992 32.4952C25.385 32.7807 25.9576 32.7917 26.5593 32.5402C27.2272 32.2611 27.9008 32.2843 28.5516 32.6157C29.1472 32.9189 29.7502 32.9451 30.373 32.7047C30.562 32.6318 30.7637 32.5918 30.9596 32.5367C30.9651 32.5509 30.9707 32.5649 30.9762 32.5791Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBarco <br> Visita\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5db9bf1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5db9bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M33.6918 17.0315C33.6414 17.3114 33.611 17.5967 33.5376 17.8705C33.0279 19.7729 31.8645 21.0941 30.0156 21.7981C29.9723 21.8146 29.9298 21.8334 29.8666 21.8595C30.0265 22.0191 30.1794 22.1624 30.3217 22.3155C30.6411 22.6593 30.9537 23.0095 31.2743 23.3522C31.3052 23.3853 31.3753 23.4047 31.4217 23.397C31.8383 23.3273 32.2547 23.2549 32.6692 23.1738C33.1298 23.0837 33.4688 23.3642 33.4401 23.8347C33.365 25.0641 32.9451 26.1726 32.2384 27.1743C31.4268 28.3247 30.3656 29.1887 29.1324 29.8515C28.456 30.2151 27.7428 30.4889 27.0105 30.7167C27.0071 30.7374 27.0002 30.7532 27.003 30.767C27.0966 31.2272 26.8422 31.5492 26.3713 31.5569C26.0435 31.5622 25.7156 31.558 25.3877 31.558C23.8436 31.558 22.2995 31.5614 20.7555 31.5528C20.5993 31.552 20.4233 31.5124 20.292 31.4326C20.0321 31.2747 20.0065 31.0096 20.0671 30.7336C19.7162 30.608 19.3653 30.4942 19.0234 30.358C17.432 29.724 16.0566 28.7892 15.0037 27.42C14.1806 26.3497 13.7045 25.1425 13.6213 23.7886C13.5974 23.4003 13.9498 23.0904 14.3348 23.1595C14.7661 23.2369 15.1974 23.3154 15.6278 23.3978C15.7164 23.4148 15.7679 23.3982 15.8241 23.3193C15.9371 23.1608 16.0578 23.0046 16.195 22.8671C18.029 21.0292 19.8655 19.1939 21.7032 17.3597C22.5311 16.5335 23.7222 16.3436 24.7215 16.8726C24.9937 17.0166 25.1237 17.2983 25.0463 17.576C24.9696 17.851 24.7091 18.0409 24.4257 18.0142C24.3336 18.0055 24.2416 17.9698 24.1549 17.9337C23.509 17.6644 23.0025 17.7621 22.5076 18.2569C20.7688 19.9955 19.0306 21.7347 17.2899 23.4714C17.2508 23.5103 17.185 23.5224 17.1316 23.547C17.1517 23.5716 17.1718 23.5963 17.1919 23.621C21.4204 24.133 25.6486 24.133 29.9023 23.6176C29.8649 23.5713 29.848 23.546 29.827 23.525C29.3743 23.0728 28.9223 22.6199 28.4665 22.171C28.4256 22.1307 28.3614 22.1004 28.3044 22.0926C27.9336 22.0414 27.5623 21.992 27.1898 21.9577C27.1324 21.9524 27.053 22.0153 27.0086 22.0677C26.8009 22.3126 26.5051 22.3845 26.243 22.2424C25.8927 22.0525 25.8009 21.6412 26.0566 21.3281C26.1529 21.2102 26.1466 21.1298 26.089 20.9974C25.4373 19.499 25.4927 18.0085 26.2221 16.5594C26.9743 15.065 28.167 14.0782 29.7967 13.6552C30.7296 13.4131 31.6595 13.4535 32.5762 13.762C32.7619 13.8244 32.8942 13.9378 32.9932 14.1049C33.3708 14.7421 33.5987 15.4269 33.664 16.1654C33.6672 16.2008 33.6823 16.2351 33.6918 16.27V17.0315ZM14.9352 24.5097C15.1437 25.4356 15.5649 26.231 16.1623 26.9337C17.172 28.1211 18.4546 28.9037 19.914 29.406C21.5552 29.9708 23.2425 30.1218 24.963 29.909C26.3736 29.7346 27.7054 29.3174 28.9291 28.5849C30.0073 27.9394 30.9123 27.1137 31.5463 26.0141C31.8163 25.546 32.0142 25.0502 32.131 24.51C26.3967 25.449 20.6761 25.4494 14.9352 24.5097ZM27.0356 20.1015C27.222 19.8713 27.3946 19.6591 27.5663 19.4461C28.1831 18.6807 28.7991 17.9146 29.4165 17.1496C29.6111 16.9084 29.8717 16.8307 30.1348 16.9306C30.5333 17.0818 30.6429 17.5435 30.3592 17.8982C29.7418 18.67 29.1212 19.4392 28.5021 20.2096C28.3316 20.4217 28.1619 20.6344 27.9918 20.8469C27.9972 20.863 28.0027 20.8791 28.0081 20.8952C28.3421 20.8704 28.6825 20.8786 29.009 20.8152C30.3238 20.5595 31.3034 19.8196 31.9464 18.6559C32.6024 17.4689 32.6836 16.2409 32.1065 14.9909C32.0596 14.8893 31.992 14.8382 31.8864 14.8136C31.1183 14.6353 30.3571 14.6636 29.6307 14.968C27.9542 15.6707 27.0259 16.9421 26.8586 18.7523C26.8172 19.1997 26.8791 19.6469 27.0356 20.1015Z\" fill=\"white\"><\/path><path d=\"M14.4676 9.87964C14.4748 9.72354 14.4841 9.56647 14.4889 9.40925C14.5128 8.63242 14.5358 7.85553 14.5587 7.07863C14.5698 6.70424 14.8283 6.43199 15.1652 6.44063C15.5203 6.44978 15.7737 6.72133 15.7628 7.10395C15.7192 8.64189 15.6697 10.1797 15.6234 11.7176C15.6193 11.8542 15.6228 11.9911 15.6228 12.1412C16.1205 12.0544 16.6097 11.9445 17.1039 11.7003C16.9969 11.6474 16.9211 11.6081 16.8437 11.5721C16.5293 11.426 16.3994 11.0987 16.5289 10.7769C16.646 10.4861 16.9843 10.3431 17.2958 10.4609C17.6102 10.5797 17.8972 10.7441 18.1296 10.9935C18.3436 11.2232 18.4284 11.4958 18.4185 11.8063C18.3575 13.7034 18.2987 15.6006 18.2393 17.4978C18.2284 17.8466 18.2177 18.1954 18.207 18.5442C18.1951 18.9301 17.94 19.1978 17.593 19.1887C17.2367 19.1793 16.9915 18.9117 17.0024 18.5241C17.0363 17.3138 17.0761 16.1037 17.1132 14.8935C17.1314 14.3016 17.1489 13.7097 17.166 13.1178C17.167 13.0823 17.1615 13.0466 17.1597 13.0214C16.6322 13.147 16.1103 13.2713 15.5443 13.406C15.5443 13.6818 15.5519 13.9772 15.5431 14.2722C15.4734 16.6081 15.401 18.9439 15.3282 21.2797C15.3187 21.5855 15.1744 21.7999 14.9305 21.8855C14.5073 22.034 14.1121 21.7272 14.1246 21.2538C14.1435 20.535 14.1678 19.8163 14.1899 19.0976C14.2392 17.491 14.2895 15.8845 14.3368 14.2779C14.3442 14.0258 14.3379 13.7732 14.3379 13.5006C12.735 13.5613 11.1308 13.5127 9.58964 13.0057C9.58964 13.3586 9.58068 13.7057 9.5912 14.0522C9.63675 15.5531 9.688 17.0538 9.73724 18.5545C9.80725 20.6894 9.87781 22.8242 9.94713 24.9591C9.97512 25.8205 10.0039 26.6818 10.0237 27.5434C10.027 27.6869 10.0659 27.7544 10.2105 27.7982C11.0693 28.0585 11.9509 28.1309 12.8413 28.1413C13.0528 28.1438 13.2643 28.1397 13.4758 28.1422C13.8462 28.1467 14.1145 28.4016 14.1159 28.7468C14.1173 29.0916 13.8505 29.3409 13.4755 29.3476C12.384 29.3669 11.2981 29.3233 10.2325 29.056C9.85233 28.9605 9.48191 28.84 9.15117 28.6201C8.95189 28.4876 8.84855 28.3104 8.84089 28.066C8.77056 25.8148 8.6967 23.5637 8.62284 21.3126C8.54307 18.8818 8.46202 16.451 8.38194 14.0203C8.35754 13.2805 8.33934 12.5404 8.30881 11.8009C8.29184 11.3895 8.45681 11.0766 8.77659 10.8319C9.24146 10.476 9.78594 10.3092 10.3431 10.1786C11.5408 9.89801 12.7581 9.84359 13.9824 9.88082C14.1251 9.88517 14.2678 9.89026 14.4105 9.89385C14.4251 9.89423 14.4399 9.88679 14.4676 9.87964ZM14.4094 11.0993C12.7932 11.0488 11.1853 11.0489 9.65099 11.6931C11.1755 12.3437 12.7773 12.3379 14.4094 12.2977V11.0993Z\" fill=\"white\"><\/path><path d=\"M22.2021 13.6726C22.2156 13.0225 22.4231 12.476 22.6676 11.9406C22.9612 11.2976 23.264 10.6587 23.5515 10.013C23.6236 9.8511 23.6619 9.67196 23.699 9.49723C23.7804 9.11382 23.6385 8.8307 23.3013 8.63206C22.9811 8.44345 22.8766 8.12449 23.0209 7.82168C23.1696 7.50943 23.5549 7.38944 23.8553 7.56175C24.7729 8.08802 25.1113 8.93964 24.8286 9.99508C24.6566 10.6377 24.3451 11.2201 24.0641 11.8165C23.8754 12.2172 23.695 12.6224 23.5307 13.0335C23.4634 13.202 23.4314 13.3896 23.4127 13.5715C23.3808 13.8815 23.5224 14.1127 23.7908 14.2648C23.9525 14.3565 24.0869 14.4703 24.137 14.6571C24.2012 14.8966 24.1512 15.1117 23.9659 15.279C23.7645 15.4607 23.5299 15.4902 23.2897 15.3651C22.5867 14.9987 22.2126 14.4239 22.2021 13.6726Z\" fill=\"white\"><\/path><path d=\"M13.1605 31.5329C11.9022 31.532 10.6461 31.4809 9.43511 31.0885C9.22172 31.0193 9.01529 30.9156 8.82208 30.8003C8.52447 30.6228 8.44743 30.2607 8.62368 29.9725C8.79676 29.6894 9.14106 29.6001 9.43816 29.7728C9.89261 30.037 10.4001 30.1171 10.9052 30.1921C12.0964 30.3691 13.2948 30.3921 14.4935 30.2909C14.9818 30.2496 15.4708 30.1854 15.9508 30.0886C16.2444 30.0294 16.6317 30.1808 16.7118 30.5585C16.7828 30.8934 16.5587 31.2229 16.1842 31.2768C15.4952 31.3759 14.8036 31.4604 14.1109 31.5277C13.7969 31.5582 13.4775 31.5329 13.1605 31.5329Z\" fill=\"white\"><\/path><path d=\"M11.4852 16.2739C11.3682 16.2209 11.2382 16.1853 11.1377 16.1103C11.0166 16.02 10.9107 15.9039 10.8159 15.785C10.6228 15.5429 10.652 15.2132 10.873 14.9945C11.0913 14.7783 11.4067 14.7541 11.65 14.9485C11.7689 15.0434 11.8807 15.152 11.9767 15.2698C12.1336 15.4626 12.1594 15.6843 12.0471 15.9079C11.9361 16.1287 11.7532 16.2473 11.4852 16.2739Z\" fill=\"white\"><\/path><path d=\"M12.2148 18.8714C11.757 18.8736 11.4479 18.371 11.6924 17.9885C11.805 17.8125 11.9741 17.6596 12.147 17.5382C12.3629 17.3866 12.6089 17.428 12.8203 17.5983C12.9993 17.7426 13.074 17.9959 13.0056 18.2273C12.9178 18.5246 12.4935 18.8701 12.2148 18.8714Z\" fill=\"white\"><\/path><path d=\"M11.7062 21.2496C11.6956 21.2496 11.6851 21.2502 11.6746 21.2495C11.3608 21.2313 10.9277 20.8013 10.9062 20.4875C10.8892 20.238 10.9846 20.0471 11.2007 19.9189C11.4187 19.7895 11.6391 19.7958 11.8378 19.9452C11.9752 20.0486 12.1051 20.171 12.2092 20.3071C12.3554 20.4984 12.36 20.7191 12.2474 20.9329C12.1342 21.1478 11.9484 21.25 11.7062 21.2496Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDietista <br> Ayuda\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd6bed5 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dd6bed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><circle cx=\"20\" cy=\"20\" r=\"20\" fill=\"#3190A8\"><\/circle><path d=\"M9.56687 25.2184C9.92102 24.8658 10.2626 24.522 10.6106 24.1848C10.6442 24.1522 10.7192 24.1458 10.7719 24.152C11.516 24.2403 12.2596 24.3331 13.0033 24.4243C13.3096 24.4618 13.6166 24.4936 13.9219 24.5375C14.0114 24.5504 14.064 24.5284 14.1215 24.4608C15.2018 23.192 16.2847 21.9253 17.3669 20.6581C17.9207 20.0096 18.4746 19.361 19.0283 18.7124C19.0814 18.6502 19.1336 18.5871 19.1984 18.5099C15.6447 17.1563 12.1122 15.8107 8.56641 14.4601C8.60712 14.4148 8.63469 14.3813 8.66523 14.3508C9.08793 13.9276 9.51207 13.506 9.93273 13.0809C9.99338 13.0196 10.048 12.9982 10.1376 13.0108C11.3062 13.1756 12.4753 13.3368 13.6452 13.4915C13.7211 13.5015 13.8169 13.4687 13.8833 13.4251C14.3741 13.1029 14.8491 12.7553 15.3517 12.4533C15.5852 12.3131 15.8627 12.2274 16.1316 12.1693C16.5355 12.0819 16.8102 12.3453 16.7297 12.7473C16.6739 13.0258 16.5493 13.2913 16.4473 13.5597C16.4111 13.6546 16.3506 13.7403 16.289 13.8525C16.482 13.8814 16.6673 13.8904 16.8416 13.9389C17.2329 14.0479 17.5373 13.936 17.8608 13.6927C18.2446 13.4039 18.6809 13.1786 19.1133 12.9639C19.2967 12.8729 19.5285 12.8466 19.7377 12.8488C19.9851 12.8514 20.1309 13.0387 20.1388 13.2886C20.1487 13.6035 20.0178 13.8791 19.888 14.1542C19.8616 14.2103 19.8331 14.2653 19.7975 14.3371C20.1909 14.3922 20.5624 14.445 20.9342 14.4963C21.4872 14.5728 22.0406 14.6459 22.5931 14.726C22.7089 14.7428 22.7905 14.7209 22.8777 14.6335C24.4347 13.0699 26.0249 11.5419 27.7665 10.1811C28.3885 9.69506 29.0244 9.22477 29.7402 8.8841C30.0242 8.7488 30.3301 8.64022 30.6378 8.57762C31.1639 8.47065 31.502 8.82608 31.4211 9.35872C31.3483 9.83876 31.1288 10.26 30.8868 10.6697C30.2836 11.6911 29.5346 12.6044 28.7641 13.5005C27.6801 14.7613 26.5266 15.9572 25.348 17.1292C25.2855 17.1915 25.2461 17.2483 25.2596 17.3446C25.3909 18.2757 25.5181 19.2072 25.6467 20.1387C25.648 20.148 25.6539 20.1566 25.6657 20.1848C25.7124 20.1633 25.7573 20.1389 25.8048 20.1213C26.0379 20.0345 26.2659 19.9237 26.5065 19.8693C26.9475 19.7697 27.2253 20.0341 27.1408 20.4784C27.094 20.7244 27.0126 20.9767 26.8882 21.1923C26.6344 21.6326 26.3397 22.0492 26.0652 22.4776C26.0305 22.5317 25.9908 22.6019 25.997 22.6597C26.0327 22.9858 26.0814 23.3105 26.1267 23.6354C26.1293 23.6539 26.1403 23.6712 26.146 23.6858C26.3695 23.5789 26.5856 23.4634 26.8113 23.3716C26.9546 23.3133 27.1102 23.2752 27.2639 23.2544C27.6446 23.203 27.9067 23.4604 27.826 23.8368C27.7663 24.1152 27.6801 24.4031 27.5357 24.6451C27.2352 25.1485 26.886 25.6227 26.5631 26.113C26.5218 26.1757 26.4904 26.2662 26.4999 26.3378C26.6447 27.435 26.7896 28.5322 26.9536 29.6267C26.9901 29.8706 26.9559 30.0383 26.7661 30.2139C26.3495 30.5992 25.9611 31.015 25.5384 31.4413C24.1813 27.8792 22.8349 24.345 21.4816 20.7928C21.2054 21.0276 20.9445 21.2486 20.6844 21.4707C18.9739 22.9318 17.2638 24.3936 15.5516 25.8527C15.4735 25.9192 15.4412 25.9774 15.4553 26.0868C15.5875 27.1166 15.7107 28.1476 15.8396 29.1778C15.8534 29.2878 15.8344 29.3684 15.7495 29.4507C15.4228 29.7677 15.1054 30.0941 14.7711 30.4303C14.6134 30.1211 14.4648 29.8301 14.3166 29.5389C13.9034 28.7273 13.4925 27.9147 13.0743 27.1057C13.0351 27.0299 12.9617 26.9564 12.8859 26.9174C11.8324 26.3753 10.7757 25.8395 9.71981 25.302C9.67307 25.2781 9.62769 25.2518 9.56687 25.2184Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVolver <br> Inicio\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-948751c e-flex e-con-boxed e-con e-parent\" data-id=\"948751c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7acf356 e-con-full e-flex e-con e-child\" data-id=\"7acf356\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-7ca9e52 e-con-full e-flex e-con e-child\" data-id=\"7ca9e52\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9df1b13 elementor-widget elementor-widget-heading\" data-id=\"9df1b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Antes de la operaci\u00f3n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c5d50b e-con-full e-flex e-con e-child\" data-id=\"3c5d50b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-dc34863 e-con-full e-flex e-con e-child\" data-id=\"dc34863\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-388831b e-con-full e-flex e-con e-child\" data-id=\"388831b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed8d741 elementor-widget elementor-widget-image\" data-id=\"ed8d741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"87\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-159.png\" class=\"attachment-large size-large wp-image-10307\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bc2e1f e-con-full e-flex e-con e-child\" data-id=\"2bc2e1f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-777e256 elementor-widget elementor-widget-text-editor\" data-id=\"777e256\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deja de fumar y de consumir alcohol. Deja de tomar anticoagulantes unos d\u00edas antes de la fecha de la operaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fcdc42 e-con-full e-flex e-con e-child\" data-id=\"4fcdc42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-810a7b7 e-con-full e-flex e-con e-child\" data-id=\"810a7b7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-f6ba7a7 e-con-full e-flex e-con e-child\" data-id=\"f6ba7a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-694b283 elementor-widget elementor-widget-image\" data-id=\"694b283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"87\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-159-1.png\" class=\"attachment-large size-large wp-image-10308\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f6de3e e-con-full e-flex e-con e-child\" data-id=\"6f6de3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9686ed2 elementor-widget elementor-widget-text-editor\" data-id=\"9686ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser\u00e1s ingresado en nuestro hospital a tu llegada. Te haremos los an\u00e1lisis de sangre, la consulta cara a cara con el cirujano y otras pruebas necesarias para prepararte para la operaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f203701 e-con-full e-flex e-con e-child\" data-id=\"f203701\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-203d348 e-con-full e-flex e-con e-child\" data-id=\"203d348\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-8a61b0b e-con-full e-flex e-con e-child\" data-id=\"8a61b0b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e04fec9 elementor-widget elementor-widget-image\" data-id=\"e04fec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"66\" height=\"87\" src=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/Group-159-2.png\" class=\"attachment-large size-large wp-image-10309\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d7b76e e-con-full e-flex e-con e-child\" data-id=\"1d7b76e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3615119 elementor-widget elementor-widget-text-editor\" data-id=\"3615119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aunque un trasplante capilar no tiene un tiempo de recuperaci\u00f3n largo, es crucial seguir los consejos de los cirujanos. Los hematomas, la hinchaz\u00f3n y un ligero mareo son efectos secundarios frecuentes de esta operaci\u00f3n, que desaparecen en unos d\u00edas. Los pacientes deben descansar la cabeza todo lo posible. Mirar hacia abajo puede hacer que la hinchaz\u00f3n baje hasta los ojos.<\/p>\n<p>Los cuidados posteriores son una parte esencial del proceso de recuperaci\u00f3n. Los pacientes deben tener especial cuidado con su zona operada&#8230;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe68744 e-flex e-con-boxed e-con e-parent\" data-id=\"fe68744\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9172779 elementor-widget elementor-widget-shortcode\" data-id=\"9172779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[blocksy-content-block id=\"4493\"]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Trasplante capilar FUE La FUE, o extracci?n de unidades foliculares, es una t?cnica quir?rgica moderna de trasplante capilar que se utiliza para tratar la ca?da del cabello o la calvicie. Es uno de los m?todos m?s avanzados de restauraci?n capilar y consiste en extraer fol?culos pilosos individuales de una zona donante y trasplantarlos a zonas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":10331,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","footnotes":""},"class_list":["post-10346","page","type-page","status-publish","hentry"],"blocksy_meta":{"vertical_spacing_source":"custom","content_area_spacing":"bottom","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasplante capilar FUE - Apera Health Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasplante capilar FUE - Apera Health Group\" \/>\n<meta property=\"og:description\" content=\"\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/\" \/>\n<meta property=\"og:site_name\" content=\"Apera Health Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aperahealthgroup\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T14:53:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/\",\"url\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/\",\"name\":\"Trasplante capilar FUE - Apera Health Group\",\"isPartOf\":{\"@id\":\"https:\/\/aperahealth.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg\",\"datePublished\":\"2024-06-22T12:05:31+00:00\",\"dateModified\":\"2024-07-16T14:53:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage\",\"url\":\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg\",\"contentUrl\":\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aperahealth.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perdida de Cabello\",\"item\":\"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trasplante capilar FUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aperahealth.com\/es\/#website\",\"url\":\"https:\/\/aperahealth.com\/es\/\",\"name\":\"Apera Health Group\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/aperahealth.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aperahealth.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aperahealth.com\/es\/#organization\",\"name\":\"Apera Health Group\",\"url\":\"https:\/\/aperahealth.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aperahealth.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/apera-health-group-logo.png\",\"contentUrl\":\"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/apera-health-group-logo.png\",\"width\":367,\"height\":99,\"caption\":\"Apera Health Group\"},\"image\":{\"@id\":\"https:\/\/aperahealth.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/aperahealthgroup\/\",\"https:\/\/www.instagram.com\/aperahealthgroup\/\",\"https:\/\/www.youtube.com\/@aperahealthgroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasplante capilar FUE - Apera Health Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/","og_locale":"es_ES","og_type":"article","og_title":"Trasplante capilar FUE - Apera Health Group","og_description":"Trasplante capilar FUE La FUE, o extracci?n de unidades foliculares, es una t?cnica quir?rgica moderna de trasplante capilar que se utiliza para tratar la ca?da del cabello o la calvicie. Es uno de los m?todos m?s avanzados de restauraci?n capilar y consiste en extraer fol?culos pilosos individuales de una zona donante y trasplantarlos a zonas [&hellip;]","og_url":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/","og_site_name":"Apera Health Group","article_publisher":"https:\/\/www.facebook.com\/aperahealthgroup\/","article_modified_time":"2024-07-16T14:53:15+00:00","og_image":[{"url":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/","url":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/","name":"Trasplante capilar FUE - Apera Health Group","isPartOf":{"@id":"https:\/\/aperahealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage"},"image":{"@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage"},"thumbnailUrl":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg","datePublished":"2024-06-22T12:05:31+00:00","dateModified":"2024-07-16T14:53:15+00:00","breadcrumb":{"@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#primaryimage","url":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg","contentUrl":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/iStock-1394566512.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/transplante-de-cabello-fue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aperahealth.com\/"},{"@type":"ListItem","position":2,"name":"Perdida de Cabello","item":"https:\/\/aperahealth.com\/es\/perdida-de-cabello\/"},{"@type":"ListItem","position":3,"name":"Trasplante capilar FUE"}]},{"@type":"WebSite","@id":"https:\/\/aperahealth.com\/es\/#website","url":"https:\/\/aperahealth.com\/es\/","name":"Apera Health Group","description":"","publisher":{"@id":"https:\/\/aperahealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aperahealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aperahealth.com\/es\/#organization","name":"Apera Health Group","url":"https:\/\/aperahealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aperahealth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/apera-health-group-logo.png","contentUrl":"https:\/\/aperahealth.com\/wp-content\/uploads\/2024\/06\/apera-health-group-logo.png","width":367,"height":99,"caption":"Apera Health Group"},"image":{"@id":"https:\/\/aperahealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aperahealthgroup\/","https:\/\/www.instagram.com\/aperahealthgroup\/","https:\/\/www.youtube.com\/@aperahealthgroup"]}]}},"_links":{"self":[{"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/pages\/10346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/comments?post=10346"}],"version-history":[{"count":11,"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/pages\/10346\/revisions"}],"predecessor-version":[{"id":12451,"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/pages\/10346\/revisions\/12451"}],"up":[{"embeddable":true,"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/pages\/10331"}],"wp:attachment":[{"href":"https:\/\/aperahealth.com\/es\/wp-json\/wp\/v2\/media?parent=10346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}